{"id":692,"date":"2021-04-01T15:45:17","date_gmt":"2021-04-01T15:45:17","guid":{"rendered":"https:\/\/alex.gotterfahren.info\/?page_id=692"},"modified":"2025-12-01T23:11:00","modified_gmt":"2025-12-01T23:11:00","slug":"gods-free-health-plan","status":"publish","type":"page","link":"https:\/\/gotterfahren.info\/en\/bibel-antworten\/gottes-kostenloser-gesundheitsplan","title":{"rendered":"God's free health plan"},"content":{"rendered":"<h1>Gottes kostenloser Gesundheitsplan<\/h1>\n<div>\n<p>Gute medizinische Versorgung ist unbezahlbar \u2013 doch w\u00e4re es nicht besser, wenn wir keine \u00c4rzte mehr ben\u00f6tigten? Wussten Sie, dass es einen bew\u00e4hrten Weg gibt, um viele \u00c4rzte arbeitslos zu machen? Tragen Sie Sorge zu Ihrem K\u00f6rper! Wissenschaftler warnen un\u00fcberh\u00f6rbar vor hohem Cholesterin, Tabak, Stress, \u00dcbergewicht und Alkohol. Warum also Ihr Gl\u00fcck aufs Spiel setzen? Spit\u00e4ler und psychiatrische Institutionen sind \u00fcberf\u00fcllt von solchen, welche diese Warnungen missachtet haben. M\u00f6chten Sie wirklich zu jenen geh\u00f6ren? Gott sorgt sich tats\u00e4chlich, wie Sie mit Ihrem K\u00f6rper umgehen. Er bietet Ihnen einen kostenlosen Gesundheitsplan samt Gebrauchsanleitung an\u2026 die Bibel! Entdecken Sie in dieser Studienanleitung die erstaunlichen Fakten, wie Sie sich einer guten Gesundheit und eines langen Lebens erfreuen k\u00f6nnen. Bitte lesen Sie aber erst alles ganz aufmerksam, ehe Sie voreilige Schl\u00fcsse ziehen!<\/p>\n<\/div>\n<ul>\n<li>\n<h3>1. Sind die Gesundheitsprinzipien tats\u00e4chlich Teil der biblischen Religion?<\/h3>\n<div>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_rechts size-thumbnail wp-image-10176 alignright\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q1-BibleReading-AfricanMan-BlueShirt-150x150.jpg\" alt=\"1. Sind die Gesundheitsprinzipien tats\u00e4chlich Teil der biblischen Religion?\" width=\"150\" height=\"150\" \/> <em>\u201cMein Lieber, ich w\u00fcnsche dir in allen Dingen Wohlergehen und Gesundheit, so wie es deiner Seele wohlgeht!\u201d 3.Johannes 2<\/em><\/p>\n<\/p>\n<p><strong>Antwort:<\/strong> Ja. Tats\u00e4chlich erw\u00e4hnt die Bibel die Wichtigkeit der Gesundheit beinahe an erster Stelle. Unser Verstand und unser geistliches Leben und der Leib stehen in enger Beziehung zueinander. Was den einen Teil betrifft, beeinflusst auch die andern. Wenn unser K\u00f6rper \u00fcberfordert wird, kann unser Verstand und unser geistliches Leben sich nicht nach Gottes Plan entfalten.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>2. Warum gab Gott seinem Volk Gesundheitsgesetze?<\/h3>\n<div><em>\u201d Und der HERR hat uns geboten, alle diese Satzungen zu halten,\u2026 und es uns gut geht alle Tage und er uns am Leben erh\u00e4lt, wie es heute der Fall ist.\u201d 5.Mose 6:24 \u201cUnd ihr sollt dem HERRN, eurem Gott, dienen, so wird er dein Brot und dein Wasser segnen; und ich will die Krankheit aus deiner Mitte hinweg nehmen.\u201d 2.Mose 23:25<\/em><\/p>\n<p><strong>Antwort:<\/strong> Gott gab Gesundheitsgesetze, weil er wei\u00df, was f\u00fcr den menschlichen K\u00f6rper am besten ist. Autohersteller legen bei jedem neuen Fahrzeug eine \u201cGebrauchsanweisung\u201d ins Handschuhfach, weil sie wissen, wie ihr Produkt am besten funktioniert. Gott, der unsern K\u00f6rper geschaffen hat, h\u00e4lt ebenfalls eine \u201cGebrauchsanweisung\u201d daf\u00fcr bereit. Diese Anweisung wird die Heilige Bibel genannt. Das Missachten dieser Gebrauchsanweisung hat Krankheiten, verwirrtes Denken und ein ausgebranntes Leben zur Folge, genauso wie die falsche Handhabung eines Autos ernsthafte Schwierigkeiten nach sich zieht. Wer sich an Gottes Anweisungen h\u00e4lt, bewahrt die Gesundheit und erfreut sich eines erf\u00fcllten Lebens. Gottes gro\u00dfartige Gesundheitsgesetze sind mit einem Schutzwall zu vergleichen, die uns vor Krankheiten sch\u00fctzen, durch die Satan uns Leiden zuf\u00fcgen will. Gott hat uns diese Gesetze gegeben, damit wir die Fallen des Teufels meiden.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>3. Haben Gottes Gesundheitsgesetze auch mit dem zu tun, was wir essen und trinken?<\/h3>\n<div>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_rechts size-thumbnail wp-image-10176 alignright\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q3-Woman-WafflesOJ-150x150.jpg\" alt=\"3. Haben Gottes Gesundheitsgesetze auch mit dem zu tun, was wir essen und trinken?\" width=\"150\" height=\"150\" \/> <em>\u201cH\u00f6rt doch auf mich, so sollt ihr Gutes essen,\u201d Jesaja 55:2 \u201cOb ihr nun esst oder trinkt oder sonst etwas tut \u2014 tut alles zur Ehre Gottes!\u201d 1.Korinther 10:31<\/em><\/p>\n<\/p>\n<p><strong>Antwort:<\/strong> Ja, ein Christ wird sogar anders essen und trinken als andere \u2013 und das alles zu Gottes Ehre \u2013 indem er nur das zu sich nimmt, was \u201cgut\u201d ist. Wenn Gott sagt, dass gewisse Dinge nicht als Nahrung f\u00fcr uns geeignet sind, muss er einen guten Grund daf\u00fcr haben. Er spricht nicht als Diktator, sondern als liebevoller Vater. Alle seine Ratschl\u00e4ge dienen immer zu unserem besten. Die biblische Verhei\u00dfung lautet: \u201c\u2026wer in Lauterkeit wandelt, dem versagt er nichts Gutes.\u201d Psalmen 84:12 Enth\u00e4lt Gott uns etwas vor, dann aus dem einen Grund, weil es uns schaden w\u00fcrde.<\/p>\n<p><b>Note:<\/b> Kein Mensch kann sich den Himmel durch Essen verdienen. Selbst das Essen von Engelsnahrung wird die Menschen nicht bef\u00e4higen, ins Paradies einzugehen. Einzig und allein die Annahme Jesu als Herrn und Erl\u00f6ser vermag dies. Das Missachten von Gottes Gesundheitsgesetzen kann aber dazu f\u00fchren, dass ein Mensch verloren geht, weil dies sein Unterscheidungsverm\u00f6gen zerst\u00f6rt und ihn zum S\u00fcndigen veranlasst.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>4. Was gab Gott den Menschen als ideale Nahrung zu essen, als er sie schuf?<\/h3>\n<div>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_links size-thumbnail wp-image-10176 alignleft\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q4-Fruit-Oat-Bowl-150x150.jpg\" alt=\"4. Was gab Gott den Menschen als ideale Nahrung zu essen, als er sie schuf?\" width=\"150\" height=\"150\" \/> <em>\u201cSiehe, ich habe euch alles samentragende Gew\u00e4chs gegeben, \u2026auch alle B\u00e4ume, an denen samentragende Fr\u00fcchte sind. Sie sollen euch zur Nahrung dienen;\u201d \u201cVon jedem Baum des Gartens darfst du nach Belieben essen; aber\u2026\u201d 1.Mose 1:29; 2:16<\/em><\/p>\n<\/p>\n<p><strong>Antwort:<\/strong> Zu Beginn gab Gott den Menschen Fr\u00fcchte, Samen und N\u00fcsse zu essen. Gem\u00fcse kam etwas sp\u00e4ter dazu (1.Mose 3:18).<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>5. Welche Dinge werden in der Bibel von Gott ausdr\u00fccklich als unrein bezeichnet und verboten?<\/h3>\n<div>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_rechts size-thumbnail wp-image-10176 alignright\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q5-UncleanAnimals-150x150.jpg\" alt=\"5. Welche Dinge werden in der Bibel von Gott ausdr\u00fccklich als unrein bezeichnet und verboten?\" width=\"150\" height=\"150\" \/><\/p>\n<p><strong>Antwort:<\/strong> In 3.Mose 11 und 5.Mose 14 bezeichnet Gott ganz klar, welche Tierarten unrein sind. Lesen Sie beide Kapitel ganz durch.<\/p>\n<p><b>A. Alle Tiere, welche die Klauen nicht spalten und nicht wiederk\u00e4uen<\/b> (5.Mose 14:6).<\/p>\n<p><b>B. Alle Fische und Wassertiere, welche keine Schuppen und keine Flo\u00dffedern haben.<\/b> Fast alle Fische sind rein (5.Mose 14:9).<\/p>\n<p><b>C. Alle Raubv\u00f6gel, Aasfresser und Fischverzehrer<\/b> (3.Mose 11:13-20).<\/p>\n<p><b>D. Die meisten \u201ckriechenden\u201d (wirbellosen) Tiere sind ebenfalls unrein<\/b> (3.Mose 11:21-47).<\/p>\n<p><b>Anmerkung:<\/b> <em>Diese Kapitel machen deutlich, dass die meisten Tiere, V\u00f6gel und Wassertiere, die gegessen werden, rein sind. Es gibt jedoch einige beachtenswerte Ausnahmen. Nach Gottes Anweisungen sind folgende Tiere unrein und d\u00fcrfen nicht gegessen werden: Schweine, Eichh\u00f6rnchen, Kaninchen, Seewolf, Aal, Hummer, Muscheln, Krabben, Crevetten, Austern, Fr\u00f6sche und viele andere.<\/em><\/p>\n<\/div>\n<\/li>\n<li>\n<h3>6. Ich esse aber gerne Schweinefleisch. Wird Gott mich deswegen vernichten?<\/h3>\n<div>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_links size-thumbnail wp-image-10168 alignleft\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q6-Bacon-150x150.jpg\" alt=\"6. Ich esse aber gerne Schweinefleisch. Wird Gott mich deswegen vernichten?\" width=\"150\" height=\"150\" \/> <em>\u201cDenn der HERR wird durchs Feuer richten und durch sein Schwert alles Fleisch; und der Get\u00f6teten des HERRN wird viel sein. Die sich heiligen und reinigen \u2026 und essen Schweinefleisch, Gr\u00e4uel und M\u00e4use, sollen weggerafft werden miteinander, spricht der HERR.\u201d Jesaja 66:16.17<\/em><\/p>\n<\/p>\n<p><strong>Antwort:<\/strong> Es mag schockieren, doch es ist wahr und muss gesagt werden: Die Bibel erkl\u00e4rt, dass alle, die \u201cSchweinefleisch\u201d, \u201cM\u00e4use\u201d und andere unreine Dinge essen, welche ein \u201cGr\u00e4uel\u201d sind, beim Kommen des Herrn mit Feuer vernichtet werden. Wenn Gott sagt, dass wir gewisse Dinge meiden sollen, dann sollten wir ihm unbedingt gehorchen. Bedenken wir, dass das Essen eines einzigen St\u00fcckes der verbotenen Frucht von Adam und Eva, einem vormals s\u00fcndlosen Paar, S\u00fcnde und Tod in diese Welt brachte. Wie kann man zu sagen wagen, dass dies unwichtig sei, wo Gott doch so klar die damit verbundenen Konsequenzen aufzeigt? Gott sagt, dass Menschen vernichtet werden, weil sie \u201ctaten, was mir \u00fcbel gefiel, und erw\u00e4hlten, was mir nicht gefiel.\u201d Jesaja 66:4<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>7. Hat dieses Gesetz von reinen und unreinen Tieren seinen Ursprung nicht am Sinai? Galt dieses nicht ausschlie\u00dflich den Juden und endete am Kreuz?<\/h3>\n<div>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_rechts size-thumbnail wp-image-10168 alignright\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q7-NoahsArk-150x150.jpg\" alt=\"7. Hat dieses Gesetz von reinen und unreinen Tieren seinen Ursprung nicht am Sinai? Galt dieses nicht ausschlie\u00dflich den Juden und endete am Kreuz?\" width=\"150\" height=\"150\" \/> <em>\u201cUnd der HERR sprach zu Noah: \u2026 Aus allerlei reinem Vieh nimm zu dir je sieben und sieben, das M\u00e4nnlein und sein Weiblein; von dem unreinen Vieh aber je ein Paar, das M\u00e4nnlein und sein Weiblein.\u201d 1.Mose 7:1.2<\/em><\/p>\n<\/p>\n<p><strong>Antwort:<\/strong> Nein, wirklich nicht! Die Bibel enth\u00e4lt gen\u00fcgend Beweise, dass es von Anbeginn der Sch\u00f6pfung reine und unreine Tiere gab. Noah lebte lange bevor es Juden gab, und doch wusste er um rein und unrein, denn er nahm von den reinen Tieren \u201csieben\u201d Paare und von den unreinen nur \u201ceines\u201d mit in die Arche. In Offenbarung 18:2 werden gewisse unreine V\u00f6gel erw\u00e4hnt zur Zeit kurz vor dem zweiten Kommen Christi. Der Tod Jesu hat diese Gesundheitsgesetze nicht au\u00dfer Kraft gesetzt, denn die Bibel sagt, dass alle, welche diese Gesetze \u00fcbertreten, bei Jesu Wiederkunft ausgel\u00f6scht werden. (Jesaja 66:15-17). Weder der Magen noch das Verdauungssystem der Juden unterscheiden sich von denjenigen der Heiden. Diese Gesundheitsgesetze gelten f\u00fcr alle Menschen aller Zeiten.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>8. Verbietet die Bibel den Gebrauch von alkoholischen Getr\u00e4nken?<\/h3>\n<div>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_links size-thumbnail wp-image-10169 alignleft\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q8-Alcohol-Man-150x150.jpg\" alt=\"8. Verbietet die Bibel den Gebrauch von alkoholischen Getr\u00e4nken?\" width=\"150\" height=\"150\" \/> <em>\u201cDer Wein macht zum Sp\u00f6tter, das starke Getr\u00e4nk macht wild, und keiner, der sich damit berauscht, wird weise.\u201d Spr\u00fcche 20:1 \u201cSchau nicht darauf, wie der Wein r\u00f6tlich schimmert, wie er im Becher perlt! Er gleitet leicht hinunter; zuletzt aber bei\u00dft er wie eine Schlange und sticht wie eine Otter!\u201d Spr\u00fcche 23:31.32 \u201cWisst ihr denn nicht, dass weder Unz\u00fcchtige\u2026noch Trunkenbolde,\u2026 werden das Reich Gottes erben. 1.Korinther 6:9.10<\/em><\/p>\n<p><strong>Antwort:<\/strong> Ja, die Bibel untersagt den Gebrauch von alkoholischen Getr\u00e4nken.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>9. Verurteilt die Bibel den Gebrauch von Tabak?<\/h3>\n<div>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_rechts size-thumbnail wp-image-10170 alignright\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q9-Cigarettes-Handcuff-150x150.jpg\" alt=\"9. Verurteilt die Bibel den Gebrauch von Tabak?\" width=\"150\" height=\"150\" \/><\/p>\n<p><strong>Antwort:<\/strong> Ja. Die Bibel nennt sechs Gr\u00fcnde, warum der Gebrauch von Tabak Gott missf\u00e4llt:<\/p>\n<p><b>A. Der Gebrauch von Tabak schadet der Gesundheit und verunreinigt den K\u00f6rper.<\/b><\/p>\n<p>\u201d Wisst ihr nicht, dass ihr Gottes Tempel seid, und dass der Geist Gottes in euch wohnt? Wenn jemand den Tempel Gottes verderbt, den wird Gott verderben; denn der Tempel Gottes ist heilig, und der seid ihr.\u201d 1.Korinther 3:16.17<\/p>\n<p><b>B. Nikotin ist ein Suchtmittel, das die Menschen versklavt.<\/b><\/p>\n<p>In R\u00f6mer 6:16 steht, dass wir Knechte dessen oder desjenigen werden, welchem wir anhangen. Wer Tabak gebraucht ist ein Knecht oder Abh\u00e4ngiger des Nikotins. Jesus sagt: \u201cDu sollst den Herrn, deinen Gott, anbeten und ihm allein dienen!\u201d Matth\u00e4us 4:10<\/p>\n<p><b>C. Die Tabaksucht ist unrein. <\/b><\/p>\n<p>\u201cDarum geht hinaus von ihnen und sondert euch ab, spricht der Herr, und r\u00fchrt nichts Unreines an! Und ich will euch aufnehmen.\u201d 2.Korinther 6:17 Es ist undenkbar, dass Christus in irgendeiner Form Tabak gebraucht h\u00e4tte, nicht wahr?<\/p>\n<p><b>D. Der Gebrauch von Tabak ist Geldverschwendung. <\/b><\/p>\n<p>\u201cWarum wiegt ihr Geld ab f\u00fcr das, was kein Brot ist?\u201d Jesaja 55:2 Wir sind Gottes Verwalter \u00fcber das uns gegebene Geld, und \u201c(Es) wird von einem Haushalter nur verlangt, dass er treu erfunden wird.\u201d 1.Korinther 4:2<\/p>\n<p><b>E. Der Gebrauch von Tabak bringt niemanden n\u00e4her zu Christus. <\/b><\/p>\n<p>\u201cEnthaltet euch der fleischlichen Begierden, die gegen die Seele streiten.\u201d 1.Petrus 2:11 Der Gebrauch von Tabak ist eine Lust des Fleisches.<\/p>\n<p><b>F. Der Gebrauch von Tabak verk\u00fcrzt das Leben. <\/b><\/p>\n<p>Wissenschaftliche Erkenntnisse best\u00e4tigen die Tatsache, dass der Gebrauch von Tabak die Lebenszeit bis zu einem Drittel verk\u00fcrzt. Dies ist gegen das Gebot Gottes, das sagt: Du sollst nicht t\u00f6ten (2.Mose 20:13). Auch wenn es sich dabei um ein langsames T\u00f6ten handelt, so ist es dennoch T\u00f6ten. Eines der besten Mittel, Ihr Begr\u00e4bnis hinauszuschieben ist, den Gebrauch von Tabak aufzugeben.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>10. Welches sind einige der einfachen, jedoch sehr wichtigen Gesundheitsgesetze, die wir in der Bibel finden?<\/h3>\n<div>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_links size-thumbnail wp-image-10171 alignleft\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q10-Family-Mealtime-150x150.jpg\" alt=\"10. Welches sind einige der einfachen, jedoch sehr wichtigen Gesundheitsgesetze, die wir in der Bibel finden?\" width=\"150\" height=\"150\" \/><\/p>\n<p><strong>Antwort:<\/strong> Hier sind 11 biblische Gesundheitsregeln:<\/p>\n<p><b>A. Nehmen Sie Ihre Mahlzeiten in regelm\u00e4\u00dfigen Abst\u00e4nden ein und verwenden Sie kein tierisches Fett oder Blut. <\/b><\/p>\n<p>\u201c\u2026 zur rechten Zeit speisen.\u201d Prediger 10:17 \u201cDas ist eine ewige Satzung f\u00fcr eure [k\u00fcnftigen] Geschlechter \u2026 dass ihr weder Fett noch Blut essen sollt.\u201d 3.Mose 3:17<\/p>\n<p><b>Anmerkung:<\/b> <em>Neue wissenschaftliche Studien haben die Tatsache best\u00e4tigt, dass die meisten Herzinfarkte auf einen hohen Cholesterinspiegel im Blut zur\u00fcckzuf\u00fchren sind, und dass die Verwendung von \u201cFetten\u201d diesen erh\u00f6hten Wert verursacht. Es scheint, dass der Herr wei\u00df, wovon er spricht, nicht wahr?<\/em><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_rechts size-thumbnail wp-image-10171 alignright\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q10-Overeating-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\"> <b>B. \u00dcberiss dich nicht. <\/b><\/p>\n<p>\u201cSetze ein Messer an deine Kehle, wenn du gierig bist.\u201d Spr\u00fcche 23:2 In Lukas 21:34 warnt Christus ausdr\u00fccklich vor \u201cFresssucht\u201d (\u00dcberessen) in den letzten Tagen. Die Gewohnheit des \u00dcberessens ist die Ursache f\u00fcr viele Krankheiten.<\/p>\n<p><b>C. Hege weder Neid noch Groll.<\/b><\/p>\n<p>Diese \u00dcbel unterbinden K\u00f6rperfunktionen. Die Bibel sagt, dass der Neid wie \u201cFra\u00df in den Gebeinen\u201d ist. Spr\u00fcche 14:30 Christus verlangt sogar von uns, dass, wenn andere etwas gegen uns haben, wir dies bereinigen. (Matth\u00e4us 5:23.24).<\/p>\n<p><b>D. Hege eine frohe, freudige Einstellung. <\/b><\/p>\n<p>\u201cEin fr\u00f6hliches Herz f\u00f6rdert die Genesung.\u201d Spr\u00fcche 17:22 Viele Krankheiten sind auf Depressionen zur\u00fcckzuf\u00fchren. Eine frohe, freudige Lebenseinstellung hingegen ist f\u00fcr die Gesundheit f\u00f6rderlich und verl\u00e4ngert das Leben.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_links size-thumbnail wp-image-10171 alignleft\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q10-Friends-Women-Hug-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\"><br \/><b>E. Vertraue dem Herrn voll und ganz. <\/b><\/p>\n<p>\u201cDie Furcht des HERRN dient zum Leben; \u2026 und wird satt bleiben.\u201d Spr\u00fcche 19:23 Gottesfurcht st\u00e4rkt Gesundheit und Leben. \u201cMein Sohn, achte auf meine Worte. \u2026 Denn sie sind das Leben denen, die sie finden, und heilsam ihrem ganzen Leib.\u201d Spr\u00fcche 4:20-22 Somit ist Gesundheit die Folge von Gehorsam Gottes Geboten gegen\u00fcber und vollem Vertrauen in ihn.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_rechts size-thumbnail wp-image-10171 alignright\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q10-Balanced-ExerciseSleeping-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\"><b>F. Ausgewogenheit zwischen Arbeit, Bewegung, Schlaf und Ruhe. <\/b><\/p>\n<p>\u201cSechs Tage sollst du arbeiten und alle deine Werke tun; aber am siebten Tag ist der Sabbat des HERRN, deines Gottes; da sollst du kein Werk tun.\u201d 2.Mose 20:9.10 \u201cS\u00fc\u00df ist der Schlaf des Arbeiters.\u201d Prediger 5:11 \u201cIm Schwei\u00dfe deines Angesichts sollst du (dein) Brot essen. 1.Mose 3:19 \u201cEs ist umsonst, dass ihr fr\u00fch aufsteht und sp\u00e4t aufbleibt.\u201d Psalmen 127:2 \u201cDenn was hat der Mensch von all seiner M\u00fche und dem Trachten seines Herzens, womit er sich abm\u00fcht unter der Sonne? Denn er plagt sich jeden Tag mit Kummer und \u00c4rger; sogar in der Nacht hat sein Herz keine Ruhe. Auch das ist nichtig!\u201d Prediger 2:22.23<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_links size-thumbnail wp-image-10171 alignleft\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q10-Soda-Coffee-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\"><b>G. Halte deinen K\u00f6rper rein. \u201c<\/b><\/p>\n<p>\u2026 reinigt euch.\u201d Jesaja 52:11<\/p>\n<p><b>H. Sei m\u00e4\u00dfig in allen Dingen. <\/b><\/p>\n<p>\u201cJeder aber, der sich am Wettkampf beteiligt, ist enthaltsam in allem.\u201d 1.Korinther 9:25 Ein Christ wird alles meiden, was sch\u00e4dlich ist und alles mit M\u00e4\u00dfigkeit gebrauchen, was gut ist. Gewohnheiten, welche der Gesundheit schaden, sind eine \u00dcbertretung des Gesetzes: \u201cDu sollst nicht t\u00f6ten.\u201d Solche Gewohnheiten t\u00f6ten nach und nach und k\u00f6nnen als \u201cSelbstmord auf Raten\u201d bezeichnet werden.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_rechts size-thumbnail wp-image-10171 alignright\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q10-Bread-Loaf-Rip-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\"><b>I. Meide alle sch\u00e4dlichen Stimulanzien. <\/b><\/p>\n<p>Das mag f\u00fcr einige eine \u00dcberraschung sein. Die medizinische Wissenschaft hat die Tatsache best\u00e4tigt, dass Schwarztee, Kaffee und S\u00fc\u00dfgetr\u00e4nke, welche die s\u00fcchtig machende Droge Koffein und andere sch\u00e4dliche Zus\u00e4tze enthalten, dem menschlichen K\u00f6rper schaden.<\/p>\n<p>Keinerlei N\u00e4hrwert ist darin enthalten, au\u00dfer dem Zucker oder dem beigef\u00fcgten Kaffeerahm. Viele von uns verwenden bereits zu viel Zucker. Stimulanzien geben dem K\u00f6rper einen gef\u00e4hrlichen, k\u00fcnstlichen Auftrieb. Die Beliebtheit dieser Getr\u00e4nke ist nicht ihrem Geschmack oder der Werbung zuzuschreiben, sondern der darin enthaltenen Dosis Koffein. Viele Menschen sind kr\u00e4nklich wegen ihrer Abh\u00e4ngigkeit von Kaffee, Schwarztee und S\u00fc\u00dfgetr\u00e4nken, die Koffein enthalten. Doch die wahre Trag\u00f6die besteht darin, dass M\u00e4nner und Frauen, die nach Frieden und Kraft suchen, zu Schwarztee und Kaffee greifen, was lediglich ein billiger Ersatz f\u00fcr Gebet und Bibelstudium ist. Das freut den Teufel und zerst\u00f6rt das menschliche Leben.<\/p>\n<p><b>J. Mache die Essenszeit zu einer frohen Zeit. <\/b><\/p>\n<p>\u201cdoch wenn irgendein Mensch isst und trinkt und Gutes genie\u00dft bei all seiner M\u00fche, so ist das auch eine Gabe Gottes.\u201d Prediger 3:13 Unliebsame Szenen w\u00e4hrend den Mahlzeiten st\u00f6ren die Verdauung. Dies sollte vermieden werden.<\/p>\n<p><b>K. Hilf denen, die in Not sind.<\/b><\/p>\n<p>\u201cIst nicht das ein Fasten, \u2026 dass ihr ungerechte Fesseln losmacht, \u2026 dass ihr die Unterdr\u00fcckten freilasst \u2026 dass du dem Hungrigen dein Brot brichst und arme Verfolgte in dein Haus f\u00fchrst, dass, wenn du einen Entbl\u00f6\u00dften siehst, du ihn bekleidest und dich deinem eigenen Fleisch nicht entziehst?\u201d Jesaja 58:6-8 Dies ist zu klar, um missverstanden zu werden. Wenn wir den Armen und Notleidenden helfen, f\u00f6rdert das unsere eigene Gesundheit.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>11. Welche feierliche Ermahnung ergeht an jene, welche Gottes Anweisungen missachten?<\/h3>\n<div>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_rechts size-thumbnail wp-image-10171 alignright\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q11-HospitalMan-150x150.jpg\" alt=\"11. Welche feierliche Ermahnung ergeht an jene, welche Gottes Anweisungen missachten?\" width=\"150\" height=\"150\" \/> <em>\u201cIrrt euch nicht: Gott l\u00e4sst sich nicht spotten! Denn was der Mensch s\u00e4t, das wird er auch ernten.\u201d Galater 6:7<\/em><\/p>\n<\/p>\n<p><strong>Antwort:<\/strong> Die Antwort ist zu klar, um missverstanden werden zu k\u00f6nnen. Wer Gottes Gesetze in Bezug auf das Sorgetragen zum Organismus bricht, wird einen kranken K\u00f6rper und ein ausgebranntes Leben ernten, genauso wie einer, der mit seinem Auto gro\u00dfe Probleme bekommt, wenn er es falsch behandelt. Wer weiterf\u00e4hrt, Gottes Gesundheitsgesetze zu \u00fcbertreten, wird letztlich vernichtet werden (1. Korinther 3:16.17). Gottes Gesundheitsgesetze sind uns nicht aus Willk\u00fcr gegeben. Es handelt sich um feststehende Naturgesetze des Universums, genauso wie das Gesetz der Schwerkraft. Das Missachten dieser Gesetze hat immer verheerende Folgen. Die Bibel sagt: \u201c\u2026 so ist ein unverdienter Fluch: Er trifft nicht ein.\u201d Spr\u00fcche 26:2 Schwierigkeiten r\u00fchren daher, dass man die Gesundheitsgesetze missachtet. Gott in seiner Gnade informiert uns \u00fcber diese Gesetze, damit wir vor den Folgen der Missachtung seiner Anweisungen bewahrt bleiben.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>12. Wie sind unsere Kinder und Gro\u00dfkinder gesundheitlich in Mitleidenschaft gezogen?<\/h3>\n<div>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_links size-thumbnail wp-image-10171 alignleft\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q12-Grandpa-Girl-Cooking-150x150.jpg\" alt=\"12. Wie sind unsere Kinder und Gro\u00dfkinder gesundheitlich in Mitleidenschaft gezogen?\" width=\"150\" height=\"150\" \/> <em>\u201cDu sollst es nicht essen, damit es dir und deinen Kindern nach dir gut geht.\u201d 5.Mose 12:25 \u201cDenn ich, der HERR, dein Gott, bin ein eifers\u00fcchtiger Gott, der die Schuld der V\u00e4ter heimsucht an den Kindern bis in das dritte und vierte Glied derer, die mich hassen.\u201d 2.Mose 20:5<\/em><\/p>\n<p><strong>Antwort:<\/strong> Gott sagt ganz klar, dass Kinder und Gro\u00dfkinder (bis in die vierte Generation) f\u00fcr die Torheit ihrer Eltern bezahlen, welche Gottes Gesundheitsgesetze missachten. Wenn M\u00fctter und V\u00e4ter Gottes Gesundheitsprinzipien f\u00fcr ihr Leben ablehnen, erben ihre Kinder und Gro\u00dfkinder geschw\u00e4chte, kr\u00e4nkliche K\u00f6rper. M\u00f6chten Sie das Ihren Kindern und Gro\u00dfkindern antun?<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>13. Welch weitere ern\u00fcchternde Tatsachen offenbart uns Gottes Wort?<\/h3>\n<div>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_rechts size-thumbnail wp-image-10171 alignright\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q13-Bible-ManReading-BrownShirt-150x150.jpg\" alt=\"13. Welch weitere ern\u00fcchternde Tatsachen offenbart uns Gottes Wort?\" width=\"150\" height=\"150\" \/> <em>\u201cUnd es wird niemals jemand in sie hineingehen, der verunreinigt, noch jemand, der Gr\u00e4uel und L\u00fcge ver\u00fcbt.\u201d Offenbarung 21:27 \u201cDenen aber, deren Herz ihren Gr\u00e4ueln und Scheusalen nachwandelt, will ich ihren Wandel auf ihren Kopf vergelten! spricht GOTT, der HER.\u201d Hesekiel 11:21<\/em><\/p>\n<\/p>\n<p><strong>Antwort:<\/strong> Nichts unreines, fehlerhaftes wird in Gottes Reich Eingang finden. Alle sch\u00e4dlichen Gewohnheiten verunreinigen einen Menschen. Der Verzehr von ungeeigneter Nahrung verunreinigt (Daniel 1:8). Das ist ern\u00fcchternd, jedoch wahr. Das Handeln nach eigenem Gutd\u00fcnken, nach dem, \u201cwas Gott \u00fcbel gef\u00e4llt\u201d, wird die Menschen ihr ewiges Heil kosten (Jesaja 66:3.4,15-17).<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>14. Was sollte jeder aufrichtige Christ sogleich anstreben?<\/h3>\n<div>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_links size-thumbnail wp-image-10171 alignleft\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q14-Woman-African-PurpleSweater-150x150.jpg\" alt=\"14. Was sollte jeder aufrichtige Christ sogleich anstreben?\" width=\"150\" height=\"150\" \/> <em>\u201cso wollen wir uns reinigen von aller Befleckung des Fleisches und des Geistes.\u201d 2.Korinther 7:1 \u201cUnd jeder, der diese Hoffnung auf ihn hat, reinigt sich, gleichwie auch Er rein ist.\u201d 1.Johannes 3:3. \u201cLiebet ihr mich, so haltet meine Gebote.\u201d Johannes 14:15<\/em><\/p>\n<\/p>\n<p><strong>Antwort:<\/strong> Aufrichtige Christen werden ihr Leben ohne Verzug in \u00dcbereinstimmung mit Gottes Anweisungen bringen, weil sie ihn lieben. Sie sind sich bewusst, dass seine Gesetze zu ihrem Wohl und Gl\u00fcck gegeben sind und um sie vor Krankheiten zu bewahren, die Satan \u00fcber sie bringen m\u00f6chte (Apostelgeschichte 10:38). Gottes Ratschl\u00e4ge und Anweisungen sind immer zu unserm Wohl, ebenso wie die Anweisungen guter Eltern f\u00fcr ihre Kinder. Und wenn wir einmal erkannt haben, was in den Augen Gottes richtig ist, wird er uns daf\u00fcr zur Verantwortung ziehen. \u201cWer nun Gutes zu tun wei\u00df und es nicht tut, f\u00fcr den ist es S\u00fcnde.\u201d Jakobus 4:17<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>15. Ich mache mir Sorgen, weil einige meiner \u00fcblen Gewohnheiten mich so fest im Griff haben. Was soll ich tun?<\/h3>\n<div>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_rechts size-thumbnail wp-image-10171 alignright\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q15-BallAndChain-Man-150x150.jpg\" alt=\"15. Ich mache mir Sorgen, weil einige meiner \u00fcblen Gewohnheiten mich so fest im Griff haben. Was soll ich tun?\" width=\"150\" height=\"150\" \/> <em>\u201cAllen aber, die ihn aufnahmen, denen gab er das Anrecht, Kinder Gottes zu werden.\u201d Johannes 1:12 \u201cIch vermag alles durch den, der mich stark macht,\u2026 Christus.\u201d Philipper 4:13<\/em><\/p>\n<\/p>\n<p><strong>Antwort:<\/strong> Gehen Sie mit all diesen Gewohnheiten zu Christus und legen Sie sie ihm zu F\u00fcssen. Er wird ihnen mit Freuden ein neues Herz und die notwendige Kraft schenken, um mit jeder \u00fcblen Gewohnheit zu brechen und ein Sohn oder eine Tochter Gottes zu werden (Hesekiel 11:18.19). Wie froh machend ist die Gewissheit, dass \u201cmit Gott alle Dinge m\u00f6glich sind.\u201d Markus 10:27 Jesus sagt: \u201cund wer zu mir kommt, den werde ich nicht hinaussto\u00dfen\u2026\u201d Johannes 6:37 Jesus ist bereit, die Ketten zu sprengen, mit denen wir gebunden sind. Er sehnt sich danach, uns frei zu machen, sofern wir unsere Zustimmung dazu geben. Unsere \u00c4ngste, \u00fcblen Gewohnheiten und nerv\u00f6sen Spannungen werden verschwinden, wenn wir seine Gebote halten. Er sagt: \u201cDies habe ich zu euch geredet, damit \u2026 eure Freude v\u00f6llig werde.\u201d Johannes 15:11 Der Teufel behauptet, dass im Ungehorsam wahre Freiheit zu finden sei, doch das ist ein Trugschluss (Johannes 8:44).<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>16. Welche froh machenden Verhei\u00dfungen werden uns bez\u00fcglich Gottes neuem Reich gegeben?<\/h3>\n<div>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"bild_links size-thumbnail wp-image-10171 alignleft\" src=\"\/wp-content\/uploads\/2021\/06\/ba-gks-sg13-q16-Heaven-MeadowPlay-150x150.jpg\" alt=\"16. Welche froh machenden Verhei\u00dfungen werden uns bez\u00fcglich Gottes neuem Reich gegeben?\" width=\"150\" height=\"150\" \/> <em>\u201cUnd kein Einwohner wird sagen: Ich bin schwach.\u201d Jesaja 33:24 \u201cund der Tod wird nicht mehr sein, weder Leid noch Geschrei noch Schmerz wird mehr sein;\u201d Offenbarung 21:4 \u201caber die auf den HERRN harren, kriegen neue Kraft, dass sie auffahren mit Fl\u00fcgeln wie Adler, dass sie laufen und nicht matt werden, dass sie wandeln und nicht m\u00fcde werden.\u201d Jesaja 40:31<\/em><\/p>\n<\/p>\n<p><strong>Antwort:<\/strong> Die Bewohner von Gottes neuem Reich werden nach seinen Gesundheitsgesetzen leben. Dort wird es keine Krankheiten geben. Sie werden mit nie endender Kraft und Jugend gesegnet sein und in der Gemeinschaft mit Gott in unaussprechlicher Freude und Gl\u00fcck in alle Ewigkeit leben.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>17. Da ein gesunder Lebensstil tats\u00e4chlich Teil der biblischen Lehre ist, bin ich bereit, Gottes Gesundheitsgesetze zu befolgen.<\/h3>\n<div>\n<p><strong>Antwort:<\/strong><\/p>\n<\/div>\n<\/li>\n<\/ul>\n<h1>\n<h4>Fragen zum Nachdenken<\/h4>\n<\/h1>\n<ul>\n<li>\n<h3>1. In 1.Timotheus 4:4 steht: &#8218;Denn alles, was Gott geschaffen hat, ist gut, und nichts ist verwerflich, wenn es mit Danksagung empfangen wird.&#8216; Wie ist diese Aussage zu verstehen?<\/h3>\n<div>\n<p>Dieser Schriftabschnitt (Vers 3) bezieht sich auf Speisen, die \u201cGott geschaffen hat, zu nehmen mit Danksagung\u201d den Gl\u00e4ubigen. Diese Speisen sind rein, wie wir bereits entdeckt haben und sind in 3.Mose 11 und in 5.Mose 14 aufgelistet. Vers 4 macht deutlich, dass alle Kreatur Gottes gut und nicht verwerflich ist, sofern sie unter den Kreaturen sind, die \u201cmit Danksagung empfangen werden\u201d (d.h. die reinen Tiere). Vers 5 sagt, warum diese Tiere (oder Speisen) in Ordnung sind: sie sind \u201cgeheiligt\u201d durch das Wort Gottes, welches diese als rein erkl\u00e4rt, und durch ein \u201cDankgebet\u201d. Bitte beachten Sie aber, dass Gott jene vernichten wird, welche \u201csich selbst heiligen\u201d, w\u00e4hrend sie unreine Speisen essen (Jesaja 66:17).<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>2. In Matth\u00e4us 15:11 lesen wir: &#8218;Nicht das, was zum Mund hineinkommt, verunreinigt den Menschen, sondern was aus dem Mund herauskommt, das verunreinigt den Menschen.&#8216; Wie ist dies zu verstehen?<\/h3>\n<div>\n<p>In Matth\u00e4us 15:1-20 geht es um das Thema des Essens ohne vorheriges Waschen der H\u00e4nde (Vers 2). Es geht hier nicht ums Essen, sondern ums Waschen. Die Schriftgelehrten unterwiesen die Leute, dass jedes Essen, das ohne vorheriges, besonderes Waschritual eingenommen werde, den Menschen verunreinige. Jesus erkl\u00e4rte die zeremoniellen Waschungen jedoch als bedeutungslos. In Vers 19 z\u00e4hlt er gewisse \u00dcbel auf \u2013 Mord, Ehebruch, Dieberei, etc. Dann schlussfolgerte er: \u201cDas sind die St\u00fccke, die den Menschen verunreinigen. Aber mit ungewaschenen H\u00e4nden essen verunreinigt den Menschen nicht.\u201d Vers 20<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>3. Wurden in der Vision des Petrus nicht alle Tiere von Jesus gereinigt nach dem Bericht in Apostelgeschichte 10?<\/h3>\n<div>\n<p>Nein! In dieser Vision geht es nicht um Tiere, sondern um Menschen. Gott gab Petrus diese Vision, um ihm verst\u00e4ndlich zu machen, dass die Heiden nicht unrein w\u00e4ren, wie die Juden meinten. Gott hatte Kornelius, einen Heiden, angewiesen, M\u00e4nner zu Petrus zu schicken. Petrus h\u00e4tte es jedoch abgelehnt, diese zu empfangen, h\u00e4tte Gott ihm nicht zuvor diese Vision gegeben, denn das j\u00fcdische Gesetz verbot es, Heiden ins Haus zu nehmen (Vers 28). Als die M\u00e4nner ankamen, wurden sie von Petrus aufgenommen. Dabei erkl\u00e4rte er ihnen, dass er dies normalerweise nicht getan h\u00e4tte, w\u00fcrde Gott ihm nicht gezeigt haben, dass \u201ckein Mensch gemein oder unrein zu hei\u00dfen ist.\u201d Vers 28. Im n\u00e4chsten Kapitel (Apostelgeschichte 11), wurde Petrus von den Gemeindegliedern wegen seines Umgangs mit den Heiden getadelt. Da erz\u00e4hlte er ihnen die ganze Geschichte mit der Vision und deren Bedeutung. In Apostelgeschichte 11:18 lesen wir dann: \u201cDa sie das h\u00f6rten, schwiegen sie still und lobten Gott und sprachen: So hat Gott auch den Heiden Bu\u00dfe gegeben zum Leben!\u201d<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>4. Wof\u00fcr hat denn Gott das Schwein geschaffen, wenn nicht zur Speise?<\/h3>\n<div>\n<p>Gott schuf dieses aus demselben Grund wie den Bussard \u2013 als einen Aasfresser, um die Umwelt von Abfall zu s\u00e4ubern. Und das Schwein kommt dieser Bestimmung in bewunderungsw\u00fcrdiger Weise nach.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>5. In R\u00f6mer 14:3.14.20 steht: &#8218;Wer isst, verachte den nicht, der nicht isst.&#8216; &#8218;Ich wei\u00df, \u2026 dass nichts an und f\u00fcr sich unrein ist.&#8216; &#8218;Es ist zwar alles rein, aber&#8230;&#8216; Wie kann dies erkl\u00e4rt werden? In den Versen 3-6 geht es um Mensch<\/h3>\n<div>\n<p>In den Versen 3-6 geht es um Menschen, die gewisse Dinge essen, die andere meiden. In diesem Abschnitt wird weder dem einen noch dem andern Recht gegeben, sondern der Rat erteilt, einander nicht zu verurteilen. Gott sollte die Sache beurteilen (Verse 4,10-12). In den Versen 14 und 20 geht es um Speisen, die erst den G\u00f6tzen dargebracht worden waren (was sie zeremoniell unrein machte) \u2013 nicht um reine oder unreine Tiere von 3.Mose 11. (Bitte lesen Sie 1.Korinther 8:1.4.10.13). Es geht in dieser Diskussion darum, dass vorheriges Darbringen der Speisen den G\u00f6tzen diese Speisen nicht \u201cunrein\u201d machten, weil ein G\u00f6tze \u201cnichts in der Welt ist.\u201d 1.Korinther 8:4 Doch wenn sich ein Mensch ein Gewissen dar\u00fcber macht, dann sollte er es besser nicht anr\u00fchren. Selbst wenn ein Bruder Ansto\u00df daran n\u00e4hme, sollte er darauf verzichten.<\/p>\n<\/div>\n<\/li>\n<li>\n<h3>6. Sind Gesundheitsgesetze, Essen und Trinken f\u00fcr mich pers\u00f6nlich wirklich von Bedeutung? Gen\u00fcgt es nicht, wenn ich den Herrn liebe?<\/h3>\n<div>\n<p>Es geht dabei um Leben und Tod, weil der Gehorsam mit im Spiel ist. \u201cund nachdem er zur Vollendung gelangt ist, ist er allen, die ihm gehorchen, der Urheber ewigen Heils geworden.\u201d Hebr\u00e4er 5:9 \u201cNicht jeder, der zu mir sagt: Herr, Herr! wird in das Reich der Himmel eingehen, sondern wer den Willen meines Vaters im Himmel tut.\u201d Matth\u00e4us 7:21 Es geht hier um die Liebe, die wir zu Christus haben, denn er sagt: \u201cLiebet ihr mich, so haltet meine Gebote.\u201d Johannes 14:15 Wenn wir den Herrn wirklich lieben, dann gehorchen wir ihm gerne, ohne Ausfl\u00fcchte oder Entschuldigungen zu suchen. Es handelt sich hier um den gr\u00f6\u00dften Pr\u00fcfstein.<\/p>\n<\/div>\n<\/li>\n<\/ul>\n<h1>\n<h4>QUIZ FRAGEN<\/h4>\n<\/h1>\n<div>Teste mit diesem Quiz, ob Du das Anliegen der Bibel zu diesem Thema verstanden hast.<\/div>\n<div>\n            <div class='ays-quiz-container  '                 data-quest-effect='shake'                  data-hide-bg-image='true'                 id='ays-quiz-container-10'>                <div class='ays-live-bar-wrap'><div class='ays-live-bar-fill' style='width: 0%;'><span><span class='ays-live-bar-percent ays-live-bar-count'><\/span>\/12<\/span><\/div><\/div>                                <div class='ays-questions-container'>                                        <form                         action=''                         method='post'                         autocomplete='off'                        id='ays_finish_quiz_10'                         class=' enable_questions_result '                    >            <input type='hidden' value='list' class='answer_view_class'>            <input type='hidden' value='' class='ays_qm_enable_arrows'>                                    <div class='step active-step'>                <div class='ays-abs-fs ays-start-page'>                                                            <p class='ays-fs-title'>Gottes kostenloser Gesundheitsplan<\/p>                    <div class='ays-fs-subtitle'><\/div>                    <input type='hidden' name='ays_quiz_id' value='10'\/>                    <input type='hidden' name='ays_quiz_questions' value='128,127,126,125,124,123,129,130,131,132,133,134'>                                        <div class='ays_buttons_div'>                        <input type='button'   name='next' class='ays_next start_button action-button' value='Start' data-enable-leave-page=\"false\" \/>                    <\/div>                                                        <\/div>            <\/div><div class='step  ' data-question-id='128'>                                                <p class='ays-question-counter animated'>1 \/ 12<\/p>                        <div class='ays-abs-fs'>                                                        <div class='ays_quiz_question'>                                <h4><strong>Alkoholische Getr\u00e4nke\u00a0<\/strong><\/h4>                            <\/div>                                                        <div class='ays-quiz-answers ays_list_view_container'>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-128]' id='ays-answer-471-10' value='471'\/>                <label for='ays-answer-471-10' class='  ays_position_initial '>sind dem Christen gestattet, wenn er sie m\u00e4\u00dfig gebraucht. <\/label><label for='ays-answer-471-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-128]' id='ays-answer-472-10' value='472'\/>                <label for='ays-answer-472-10' class='  ays_position_initial '>f\u00fcr einen Menschen nur dann verkehrt, wenn er davon \u00fcberzeugt ist. <\/label><label for='ays-answer-472-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='radio' name='ays_questions[ays-question-128]' id='ays-answer-473-10' value='473'\/>                <label for='ays-answer-473-10' class='  ays_position_initial '>sollen von Christen nicht gebraucht werden.<\/label><label for='ays-answer-473-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div><\/div>                                                        <div class='ays_buttons_div'>                                                <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_previous action-button ays_display_none' value='Prev' \/>                                                <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_next action-button ' value='Next' \/>                    <\/div>                            <div class='wrong_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='right_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='ays_questtion_explanation' style='display:none'>                                                            <\/div>                                                    <\/div>                    <\/div><div class='step  ' data-question-id='127'>                                                <p class='ays-question-counter animated'>2 \/ 12<\/p>                        <div class='ays-abs-fs'>                                                        <div class='ays_quiz_question'>                                <h4><strong>Gott bezeichnet diese Gesch\u00f6pfe als unrein: <\/strong><\/h4>                            <\/div>                                                        <div class='ays-quiz-answers ays_list_view_container'>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='checkbox' name='ays_questions[ays-question-127]' id='ays-answer-459-10' value='459'\/>                <label for='ays-answer-459-10' class='  ays_position_initial '>Kuh<\/label><label for='ays-answer-459-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='checkbox' name='ays_questions[ays-question-127]' id='ays-answer-460-10' value='460'\/>                <label for='ays-answer-460-10' class='  ays_position_initial '>Schwein <\/label><label for='ays-answer-460-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='checkbox' name='ays_questions[ays-question-127]' id='ays-answer-461-10' value='461'\/>                <label for='ays-answer-461-10' class='  ays_position_initial '>Huhn <\/label><label for='ays-answer-461-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='checkbox' name='ays_questions[ays-question-127]' id='ays-answer-462-10' value='462'\/>                <label for='ays-answer-462-10' class='  ays_position_initial '>Eichh\u00f6rnchen <\/label><label for='ays-answer-462-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='checkbox' name='ays_questions[ays-question-127]' id='ays-answer-463-10' value='463'\/>                <label for='ays-answer-463-10' class='  ays_position_initial '>Kaninchen <\/label><label for='ays-answer-463-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='checkbox' name='ays_questions[ays-question-127]' id='ays-answer-464-10' value='464'\/>                <label for='ays-answer-464-10' class='  ays_position_initial '>Seewolf <\/label><label for='ays-answer-464-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='checkbox' name='ays_questions[ays-question-127]' id='ays-answer-465-10' value='465'\/>                <label for='ays-answer-465-10' class='  ays_position_initial '>Reh <\/label><label for='ays-answer-465-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='checkbox' name='ays_questions[ays-question-127]' id='ays-answer-466-10' value='466'\/>                <label for='ays-answer-466-10' class='  ays_position_initial '>Truthahn <\/label><label for='ays-answer-466-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='checkbox' name='ays_questions[ays-question-127]' id='ays-answer-467-10' value='467'\/>                <label for='ays-answer-467-10' class='  ays_position_initial '>Muscheln <\/label><label for='ays-answer-467-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='checkbox' name='ays_questions[ays-question-127]' id='ays-answer-468-10' value='468'\/>                <label for='ays-answer-468-10' class='  ays_position_initial '>Crevetten <\/label><label for='ays-answer-468-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='checkbox' name='ays_questions[ays-question-127]' id='ays-answer-469-10' value='469'\/>                <label for='ays-answer-469-10' class='  ays_position_initial '>Hummer <\/label><label for='ays-answer-469-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='checkbox' name='ays_questions[ays-question-127]' id='ays-answer-470-10' value='470'\/>                <label for='ays-answer-470-10' class='  ays_position_initial '>Ziege<\/label><label for='ays-answer-470-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div><\/div>                                                        <div class='ays_buttons_div'>                                                <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_previous action-button ays_display_none' value='Prev' \/>                                                <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_next action-button ' value='Next' \/>                    <\/div>                            <div class='wrong_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='right_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='ays_questtion_explanation' style='display:none'>                                                            <\/div>                                                    <\/div>                    <\/div><div class='step  ' data-question-id='126'>                                                <p class='ays-question-counter animated'>3 \/ 12<\/p>                        <div class='ays-abs-fs'>                                                        <div class='ays_quiz_question'>                                <h4><strong>Die urspr\u00fcngliche Nahrung der Menschen\u00a0<\/strong><\/h4>                            <\/div>                                                        <div class='ays-quiz-answers ays_list_view_container'>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='radio' name='ays_questions[ays-question-126]' id='ays-answer-456-10' value='456'\/>                <label for='ays-answer-456-10' class='  ays_position_initial '>bestand aus Fr\u00fcchten, Samen und N\u00fcssen. <\/label><label for='ays-answer-456-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-126]' id='ays-answer-457-10' value='457'\/>                <label for='ays-answer-457-10' class='  ays_position_initial '>enthielt alkoholische Getr\u00e4nke und Fleisch. <\/label><label for='ays-answer-457-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-126]' id='ays-answer-458-10' value='458'\/>                <label for='ays-answer-458-10' class='  ays_position_initial '>bestand aus alle dem, wonach Adam und Eva gel\u00fcstete.<\/label><label for='ays-answer-458-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div><\/div>                                                        <div class='ays_buttons_div'>                                                <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_previous action-button ays_display_none' value='Prev' \/>                                                <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_next action-button ' value='Next' \/>                    <\/div>                            <div class='wrong_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='right_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='ays_questtion_explanation' style='display:none'>                                                            <\/div>                                                    <\/div>                    <\/div><div class='step  ' data-question-id='125'>                                                <p class='ays-question-counter animated'>4 \/ 12<\/p>                        <div class='ays-abs-fs'>                                                        <div class='ays_quiz_question'>                                <h4><strong>Ein wahrer Christ wird<\/strong><\/h4>                            <\/div>                                                        <div class='ays-quiz-answers ays_list_view_container'>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-125]' id='ays-answer-453-10' value='453'\/>                <label for='ays-answer-453-10' class='  ays_position_initial '>alles essen und trinken, was ihm beliebt. <\/label><label for='ays-answer-453-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-125]' id='ays-answer-454-10' value='454'\/>                <label for='ays-answer-454-10' class='  ays_position_initial '>den Herrn \u00fcber alles lieben und seine Gesundheitsgesetze ignorieren, weil sie seit dem Kreuz aufgehoben sind. <\/label><label for='ays-answer-454-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='radio' name='ays_questions[ays-question-125]' id='ays-answer-455-10' value='455'\/>                <label for='ays-answer-455-10' class='  ays_position_initial '>nur das essen und trinken, was K\u00f6rper, Geist und Charakter st\u00e4rkt und Gott ehrt.<\/label><label for='ays-answer-455-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div><\/div>                                                        <div class='ays_buttons_div'>                                                <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_previous action-button ays_display_none' value='Prev' \/>                                                <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_next action-button ' value='Next' \/>                    <\/div>                            <div class='wrong_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='right_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='ays_questtion_explanation' style='display:none'>                                                            <\/div>                                                    <\/div>                    <\/div><div class='step  ' data-question-id='124'>                                                <p class='ays-question-counter animated'>5 \/ 12<\/p>                        <div class='ays-abs-fs'>                                                        <div class='ays_quiz_question'>                                <h4><strong>Gottes Gesundheitsgesetze wurden gegeben<\/strong><\/h4>                            <\/div>                                                        <div class='ays-quiz-answers ays_list_view_container'>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='radio' name='ays_questions[ays-question-124]' id='ays-answer-450-10' value='450'\/>                <label for='ays-answer-450-10' class='  ays_position_initial '>von einem liebenden Gott, der uns geschaffen hat und am besten wei\u00df, was zu unserm Gl\u00fcck dient. <\/label><label for='ays-answer-450-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-124]' id='ays-answer-451-10' value='451'\/>                <label for='ays-answer-451-10' class='  ays_position_initial '>allein f\u00fcr die Juden und haben heute keine Bedeutung mehr. <\/label><label for='ays-answer-451-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-124]' id='ays-answer-452-10' value='452'\/>                <label for='ays-answer-452-10' class='  ays_position_initial '>um deutlich zu machen, dass er der Boss ist, der uns beherrscht.<\/label><label for='ays-answer-452-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div><\/div>                                                        <div class='ays_buttons_div'>                                                <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_previous action-button ays_display_none' value='Prev' \/>                                                <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_next action-button ' value='Next' \/>                    <\/div>                            <div class='wrong_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='right_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='ays_questtion_explanation' style='display:none'>                                                            <\/div>                                                    <\/div>                    <\/div><div class='step  ' data-question-id='123'>                                                <p class='ays-question-counter animated'>6 \/ 12<\/p>                        <div class='ays-abs-fs'>                                                        <div class='ays_quiz_question'>                                <h4><strong>Gottes Gesundheitsgesetze sind f\u00fcr den menschlichen K\u00f6rper<\/strong><\/h4>                            <\/div>                                                        <div class='ays-quiz-answers ays_list_view_container'>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-123]' id='ays-answer-447-10' value='447'\/>                <label for='ays-answer-447-10' class='  ays_position_initial '>in der Kindheit notwendig, haben aber wenig Bedeutung f\u00fcr Erwachsene. <\/label><label for='ays-answer-447-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='radio' name='ays_questions[ays-question-123]' id='ays-answer-448-10' value='448'\/>                <label for='ays-answer-448-10' class='  ays_position_initial '>ein wichtiger Teil des wahren biblischen Glaubens. <\/label><label for='ays-answer-448-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-123]' id='ays-answer-449-10' value='449'\/>                <label for='ays-answer-449-10' class='  ays_position_initial '>haben nichts mit der Religion einer Person zu tun.<\/label><label for='ays-answer-449-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div><\/div>                                                        <div class='ays_buttons_div'>                                                <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_previous action-button ays_display_none' value='Prev' \/>                                                <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_next action-button ' value='Next' \/>                    <\/div>                            <div class='wrong_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='right_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='ays_questtion_explanation' style='display:none'>                                                            <\/div>                                                    <\/div>                    <\/div><div class='step  ' data-question-id='129'>                                                <p class='ays-question-counter animated'>7 \/ 12<\/p>                        <div class='ays-abs-fs'>                                                        <div class='ays_quiz_question'>                                <h4><strong>Der Gebrauch von Tabak ist<\/strong><\/h4>                            <\/div>                                                        <div class='ays-quiz-answers ays_list_view_container'>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-129]' id='ays-answer-474-10' value='474'\/>                <label for='ays-answer-474-10' class='  ays_position_initial '>jedem seine eigene Sache und hat nichts mit seiner Religion zu tun. <\/label><label for='ays-answer-474-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='radio' name='ays_questions[ays-question-129]' id='ays-answer-475-10' value='475'\/>                <label for='ays-answer-475-10' class='  ays_position_initial '>eine S\u00fcnde, deshalb wird ein Christ diesen in keiner Form gebrauchen. <\/label><label for='ays-answer-475-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-129]' id='ays-answer-476-10' value='476'\/>                <label for='ays-answer-476-10' class='  ays_position_initial '>dem Christen von Vorteil.<\/label><label for='ays-answer-476-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div><\/div>                                                        <div class='ays_buttons_div'>                                                <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_previous action-button ays_display_none' value='Prev' \/>                                                <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_next action-button ' value='Next' \/>                    <\/div>                            <div class='wrong_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='right_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='ays_questtion_explanation' style='display:none'>                                                            <\/div>                                                    <\/div>                    <\/div><div class='step  ' data-question-id='130'>                                                <p class='ays-question-counter animated'>8 \/ 12<\/p>                        <div class='ays-abs-fs'>                                                        <div class='ays_quiz_question'>                                <h4><strong>Gehen Sie die aufgelisteten Gesundheitsgesetze durch und markieren Sie jene, welche Gottes Gesundheitsprinzipien sind:<\/strong><\/h4>                            <\/div>                                                        <div class='ays-quiz-answers ays_list_view_container'>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='checkbox' name='ays_questions[ays-question-130]' id='ays-answer-477-10' value='477'\/>                <label for='ays-answer-477-10' class='  ays_position_initial '>Nicht \u00fcberessen. <\/label><label for='ays-answer-477-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='checkbox' name='ays_questions[ays-question-130]' id='ays-answer-478-10' value='478'\/>                <label for='ays-answer-478-10' class='  ays_position_initial '>Nach jedem Essen rauchen.<\/label><label for='ays-answer-478-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='checkbox' name='ays_questions[ays-question-130]' id='ays-answer-479-10' value='479'\/>                <label for='ays-answer-479-10' class='  ays_position_initial '>Gl\u00fccklich und fr\u00f6hlich sein. <\/label><label for='ays-answer-479-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='checkbox' name='ays_questions[ays-question-130]' id='ays-answer-480-10' value='480'\/>                <label for='ays-answer-480-10' class='  ays_position_initial '>Vor den Mahlzeiten einen Lik\u00f6r trinken. <\/label><label for='ays-answer-480-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='checkbox' name='ays_questions[ays-question-130]' id='ays-answer-481-10' value='481'\/>                <label for='ays-answer-481-10' class='  ays_position_initial '>Den K\u00f6rper reinhalten. <\/label><label for='ays-answer-481-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='checkbox' name='ays_questions[ays-question-130]' id='ays-answer-482-10' value='482'\/>                <label for='ays-answer-482-10' class='  ays_position_initial '>Viel Schweinefleisch essen. <\/label><label for='ays-answer-482-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='checkbox' name='ays_questions[ays-question-130]' id='ays-answer-483-10' value='483'\/>                <label for='ays-answer-483-10' class='  ays_position_initial '>Viel Kaffee und Tee trinken. <\/label><label for='ays-answer-483-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='checkbox' name='ays_questions[ays-question-130]' id='ays-answer-484-10' value='484'\/>                <label for='ays-answer-484-10' class='  ays_position_initial '>M\u00e4\u00dfigkeit in allen Dingen. <\/label><label for='ays-answer-484-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='checkbox' name='ays_questions[ays-question-130]' id='ays-answer-485-10' value='485'\/>                <label for='ays-answer-485-10' class='  ays_position_initial '>In regelm\u00e4\u00dfigen Zeitabst\u00e4nden essen. <\/label><label for='ays-answer-485-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='checkbox' name='ays_questions[ays-question-130]' id='ays-answer-486-10' value='486'\/>                <label for='ays-answer-486-10' class='  ays_position_initial '>Keinen Groll hegen. <\/label><label for='ays-answer-486-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='checkbox' name='ays_questions[ays-question-130]' id='ays-answer-487-10' value='487'\/>                <label for='ays-answer-487-10' class='  ays_position_initial '>Ausgewogenheit zwischen Arbeit, Bewegung und Schlaf. <\/label><label for='ays-answer-487-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='checkbox' name='ays_questions[ays-question-130]' id='ays-answer-488-10' value='488'\/>                <label for='ays-answer-488-10' class='  ays_position_initial '>Volles Vertrauen in den Herrn haben. <\/label><label for='ays-answer-488-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='checkbox' name='ays_questions[ays-question-130]' id='ays-answer-489-10' value='489'\/>                <label for='ays-answer-489-10' class='  ays_position_initial '>Weder tierisches Fett noch Blut verwenden.<\/label><label for='ays-answer-489-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div><\/div>                                                        <div class='ays_buttons_div'>                                                <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_previous action-button ays_display_none' value='Prev' \/>                                                <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_next action-button ' value='Next' \/>                    <\/div>                            <div class='wrong_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='right_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='ays_questtion_explanation' style='display:none'>                                                            <\/div>                                                    <\/div>                    <\/div><div class='step  ' data-question-id='131'>                                                <p class='ays-question-counter animated'>9 \/ 12<\/p>                        <div class='ays-abs-fs'>                                                        <div class='ays_quiz_question'>                                <h4><strong>Eine wichtige Wahrheit in Bezug auf Gottes Gesundheitsgesetze ist, dass <\/strong><\/h4>                            <\/div>                                                        <div class='ays-quiz-answers ays_list_view_container'>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='radio' name='ays_questions[ays-question-131]' id='ays-answer-490-10' value='490'\/>                <label for='ays-answer-490-10' class='  ays_position_initial '>Kinder und Gro\u00dfkinder oft k\u00f6rperlich und geistig geschw\u00e4cht sind, weil Eltern Gottes Gesundheitsgesetze missachten. <\/label><label for='ays-answer-490-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-131]' id='ays-answer-491-10' value='491'\/>                <label for='ays-answer-491-10' class='  ays_position_initial '>diese Gesetze nur den Juden galten und heute keine Bedeutung mehr haben. <\/label><label for='ays-answer-491-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-131]' id='ays-answer-492-10' value='492'\/>                <label for='ays-answer-492-10' class='  ays_position_initial '>wenn wir Christus wirklich lieben, die Gesundheitsgesetze unwichtig sind.<\/label><label for='ays-answer-492-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div><\/div>                                                        <div class='ays_buttons_div'>                                                <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_previous action-button ays_display_none' value='Prev' \/>                                                <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_next action-button ' value='Next' \/>                    <\/div>                            <div class='wrong_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='right_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='ays_questtion_explanation' style='display:none'>                                                            <\/div>                                                    <\/div>                    <\/div><div class='step  ' data-question-id='132'>                                                <p class='ays-question-counter animated'>10 \/ 12<\/p>                        <div class='ays-abs-fs'>                                                        <div class='ays_quiz_question'>                                <h4><strong>Die beste Art und Weise, s\u00fcndige Gewohnheiten zu \u00fcberwinden, ist<\/strong><\/h4>                            <\/div>                                                        <div class='ays-quiz-answers ays_list_view_container'>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-132]' id='ays-answer-493-10' value='493'\/>                <label for='ays-answer-493-10' class='  ays_position_initial '>nach und nach damit zu brechen. <\/label><label for='ays-answer-493-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='radio' name='ays_questions[ays-question-132]' id='ays-answer-494-10' value='494'\/>                <label for='ays-answer-494-10' class='  ays_position_initial '>sich Christus voll und ganz zu \u00fcbergeben, der uns Kraft zum \u00dcberwinden schenkt. <\/label><label for='ays-answer-494-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-132]' id='ays-answer-495-10' value='495'\/>                <label for='ays-answer-495-10' class='  ays_position_initial '>zu hoffen, dass sie verschwinden.<\/label><label for='ays-answer-495-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div><\/div>                                                        <div class='ays_buttons_div'>                                                <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_previous action-button ays_display_none' value='Prev' \/>                                                <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_next action-button ' value='Next' \/>                    <\/div>                            <div class='wrong_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='right_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='ays_questtion_explanation' style='display:none'>                                                            <\/div>                                                    <\/div>                    <\/div><div class='step  ' data-question-id='133'>                                                <p class='ays-question-counter animated'>11 \/ 12<\/p>                        <div class='ays-abs-fs'>                                                        <div class='ays_quiz_question'>                                <h4><strong>Gottes Gesundheitsgesetze sind<\/strong><\/h4>                            <\/div>                                                        <div class='ays-quiz-answers ays_list_view_container'>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='radio' name='ays_questions[ays-question-133]' id='ays-answer-496-10' value='496'\/>                <label for='ays-answer-496-10' class='  ays_position_initial '>wie die Gebrauchsanweisung f\u00fcr ein Auto: Sie sind zu unserem Wohl gegeben. Bei Missachtung bekommen wir ernsthafte Probleme. <\/label><label for='ays-answer-496-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-133]' id='ays-answer-497-10' value='497'\/>                <label for='ays-answer-497-10' class='  ays_position_initial '>Teil des Gesetzes Mose, das am Kreuz aufgehoben wurde. <\/label><label for='ays-answer-497-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-133]' id='ays-answer-498-10' value='498'\/>                <label for='ays-answer-498-10' class='  ays_position_initial '>eine gute Sache, haben aber nichts zu tun mit der Beziehung des Menschen zu Gott.<\/label><label for='ays-answer-498-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div><\/div>                                                        <div class='ays_buttons_div'>                                                <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_previous action-button ays_display_none' value='Prev' \/>                                                <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays_display_none\"><\/i>                        <input type='button' name='next' class='ays_next action-button ' value='Next' \/>                    <\/div>                            <div class='wrong_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='right_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='ays_questtion_explanation' style='display:none'>                                                            <\/div>                                                    <\/div>                    <\/div><div class='step  ' data-question-id='134'>                                                <p class='ays-question-counter animated'>12 \/ 12<\/p>                        <div class='ays-abs-fs'>                                                        <div class='ays_quiz_question'>                                <h4><strong>Ein aufrichtiger Christ wird\u00a0<\/strong><\/h4>                            <\/div>                                                        <div class='ays-quiz-answers ays_list_view_container'>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-134]' id='ays-answer-499-10' value='499'\/>                <label for='ays-answer-499-10' class='  ays_position_initial '>mehr Zeit f\u00fcr das Gebet verwenden und den Gesundheitsprinzipien Gottes keine Beachtung schenken. <\/label><label for='ays-answer-499-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='1'\/>                <input type='radio' name='ays_questions[ays-question-134]' id='ays-answer-500-10' value='500'\/>                <label for='ays-answer-500-10' class='  ays_position_initial '>jede Gewohnheit sogleich \u00e4ndern, wenn er erkennt, dass diese gegen Gottes Prinzipien versto\u00dfen, denn wenn wir Christus lieben, werden wir seine Regeln und Gebote halten.<\/label><label for='ays-answer-500-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div>            <div class='ays-field ays_list_view_item'>                <input type='hidden' name='ays_answer_correct[]' value='0'\/>                <input type='radio' name='ays_questions[ays-question-134]' id='ays-answer-501-10' value='501'\/>                <label for='ays-answer-501-10' class='  ays_position_initial '>sich frei f\u00fchlen, Tabak zu gebrauchen.<\/label><label for='ays-answer-501-10' class='ays_answer_image ays_empty_before_content'><\/label>                <\/div><\/div>                                                        <div class='ays_buttons_div'>                                                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays_display_none\"><\/i>                            <input type='button' name='next' class='ays_previous action-button ays_display_none'  value='Prev' \/>                            <i class='ays_display_none ays_fa ays_fa_flag_checkered ays_finish action-button ays_arrow ays_next_arrow'><\/i><input type='submit' name='ays_finish_quiz' class='  ays_next ays_finish action-button' value='See Result'\/>                        <\/div>                            <div class='wrong_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='right_answer_text ays_do_not_show' style='display:none'>                                                            <\/div>                            <div class='ays_questtion_explanation' style='display:none'>                                                            <\/div>                                                    <\/div>                    <\/div><div class='step ays_thank_you_fs'>            <div class='ays-abs-fs ays-end-page'><div data-class='lds-ellipsis' data-role='loader' class='ays-loader'><div><\/div><div><\/div><div><\/div><div><\/div><\/div><div class='ays_quiz_results_page'><div class='ays_score_message'><\/div><div class='ays_message'><\/div><p class='ays_score ays_score_display_none animated'>Your score is <\/p><p class='ays_average'>The average score is 74%<\/p><div class='ays-quiz-social-shares'>                        <!-- Branded LinkedIn button -->                        <a class='ays-share-btn ays-to-share ays-share-btn-branded ays-share-btn-linkedin'                           href='https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/gotterfahren.info\/en\/wp-json\/wp\/v2\/pages\/692'                           title='Share on LinkedIn'>                            <span class='ays-share-btn-icon'><\/span>                            <span class='ays-share-btn-text'>LinkedIn<\/span>                        <\/a>                        <!-- Branded Facebook button -->                        <a class='ays-share-btn ays-to-share ays-share-btn-branded ays-share-btn-facebook'                           href='https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/gotterfahren.info\/en\/wp-json\/wp\/v2\/pages\/692'                           title='Share on Facebook'>                            <span class='ays-share-btn-icon'><\/span>                            <span class='ays-share-btn-text'>Facebook<\/span>                        <\/a>                        <!-- Branded Twitter button -->                        <a class='ays-share-btn ays-to-share ays-share-btn-branded ays-share-btn-twitter'                           href='https:\/\/twitter.com\/share?url=https:\/\/gotterfahren.info\/en\/wp-json\/wp\/v2\/pages\/692'                           title='Share on Twitter'>                            <span class='ays-share-btn-icon'><\/span>                            <span class='ays-share-btn-text'>Twitter<\/span>                        <\/a>                    <\/div><div class='ays-progress first'>                <span class='ays-progress-value first'>0%<\/span>                <div class='ays-progress-bg first'>                    <div class='ays-progress-bar first' style='width:0%;'><\/div>                <\/div>            <\/div><p class='ays_restart_button_p'><button type='button' class='action-button ays_restart_button'>                    <i class='ays_fa ays_fa_undo'><\/i>                    <span>Restart quiz<\/span>                <\/button><\/p><\/div>            <\/div>        <\/div><style>            div#ays-quiz-container-10 * {                box-sizing: border-box;            }            \/* Styles for Internet Explorer start *\/            #ays-quiz-container-10 #ays_finish_quiz_10 {                            }            \/* Styles for Quiz container *\/            #ays-quiz-container-10{                min-height: 500px;                width:0px;                background-color:#fff;                background-position:center center;background-image: url('https:\/\/gotterfahren.info\/wp-content\/uploads\/2021\/06\/13_quiz_2.jpg');border-radius:0px;box-shadow: 0 0 15px 1px rgba(186,186,186,0.4);border: none;}            \/* Styles for questions *\/            #ays-quiz-container-10 #ays_finish_quiz_10 div.step {                min-height: 500px;            }            \/* Styles for text inside quiz container *\/            #ays-quiz-container-10 .ays-start-page *:not(input),            #ays-quiz-container-10 .ays_question_hint,            #ays-quiz-container-10 label[for^=\"ays-answer-\"],            #ays-quiz-container-10 p,            #ays-quiz-container-10 .ays-fs-title,            #ays-quiz-container-10 .ays-fs-subtitle,            #ays-quiz-container-10 .logged_in_message,            #ays-quiz-container-10 .ays_score_message,            #ays-quiz-container-10 .ays_message{               color: #515151;               outline: none;            }                        #ays-quiz-container-10 textarea,            #ays-quiz-container-10 input::first-letter,            #ays-quiz-container-10 select::first-letter,            #ays-quiz-container-10 option::first-letter {                color: initial !important;            }                        #ays-quiz-container-10 p::first-letter:not(.ays_no_questions_message) {                color: #515151 !important;                background-color: transparent !important;                font-size: inherit !important;                font-weight: inherit !important;                float: none !important;                line-height: inherit !important;                margin: 0 !important;                padding: 0 !important;            }                        #ays-quiz-container-10 .select2-container,            #ays-quiz-container-10 .ays-field * {                font-size: 15px !important;            }            #ays-quiz-container-10 .ays_quiz_question p {                font-size: 16px;                text-align: center;            }            #ays-quiz-container-10 .ays_thank_you_fs p {                text-align: center;            }            #ays-quiz-container-10 .information_form input[type='text'],            #ays-quiz-container-10 .information_form input[type='url'],            #ays-quiz-container-10 .information_form input[type='number'],            #ays-quiz-container-10 .information_form input[type='email'],            #ays-quiz-container-10 .information_form input[type='checkbox'],            #ays-quiz-container-10 .information_form input[type='tel'],            #ays-quiz-container-10 .information_form textarea,            #ays-quiz-container-10 .information_form select,            #ays-quiz-container-10 .information_form option {                color: initial !important;                outline: none;            }                        #ays-quiz-container-10 .wrong_answer_text{                color:#ff4d4d;            }            #ays-quiz-container-10 .right_answer_text{                color:#33cc33;            }            #ays-quiz-container-10 .ays_cb_and_a,            #ays-quiz-container-10 .ays_cb_and_a * {                color: rgb(81,81,81);            }            #ays-quiz-container-10 iframe {                min-height: 500px;            }            \/* Quiz rate and passed users count *\/            #ays-quiz-container-10 .ays_quizn_ancnoxneri_qanak,            #ays-quiz-container-10 .ays_quiz_rete_avg{                color:#fff;                background-color:#515151;                                                    }            #ays-quiz-container-10 div.for_quiz_rate.ui.star.rating .icon {                color: rgba(81,81,81,0.35);            }            #ays-quiz-container-10 .ays_quiz_rete_avg div.for_quiz_rate_avg.ui.star.rating .icon {                color: rgba(255,255,255,0.5);            }            \/* Loaders *\/            #ays-quiz-container-10 div.lds-spinner,            #ays-quiz-container-10 div.lds-spinner2 {                color: #515151;            }            #ays-quiz-container-10 div.lds-spinner div:after,            #ays-quiz-container-10 div.lds-spinner2 div:after {                background-color: #515151;            }            #ays-quiz-container-10 .lds-circle,            #ays-quiz-container-10 .lds-facebook div,            #ays-quiz-container-10 .lds-ellipsis div{                background: #515151;            }            #ays-quiz-container-10 .lds-ripple div{                border-color: #515151;            }            #ays-quiz-container-10 .lds-dual-ring::after,            #ays-quiz-container-10 .lds-hourglass::after{                border-color: #515151 transparent #515151 transparent;            }            \/* Progress bars *\/            #ays-quiz-container-10 #ays_finish_quiz_10 .ays-progress {                border-color: rgba(81,81,81,0.8);            }            #ays-quiz-container-10 #ays_finish_quiz_10 .ays-progress-bg {                background-color: rgba(81,81,81,0.3);            }            #ays-quiz-container-10 .ays-progress-value {                color: #515151;            }            #ays-quiz-container-10 .ays-progress-bar {                background-color: #92be56;            }            #ays-quiz-container-10 .ays-question-counter .ays-live-bar-wrap {                direction:ltr !important;            }            #ays-quiz-container-10 .ays-live-bar-fill{                color: #515151;                border-bottom: 2px solid rgba(81,81,81,0.8);                text-shadow: 0px 0px 5px #fff;            }            #ays-quiz-container-10 .ays-live-bar-percent{                display:none;            }                                    \/* Music, Sound *\/            #ays-quiz-container-10 .ays_music_sound {                color:rgb(81,81,81);            }            \/* Dropdown questions scroll bar *\/            #ays-quiz-container-10 blockquote {                border-left-color: #515151 !important;                                                  }            \/* Question hint *\/            #ays-quiz-container-10 .ays_question_hint_container .ays_question_hint_text {                background-color:#fff;                box-shadow: 0 0 15px 3px rgba(186,186,186,0.6);            }            \/* Information form *\/            #ays-quiz-container-10 .ays-form-title{                color:rgb(81,81,81);            }            \/* Quiz timer *\/            #ays-quiz-container-10 div.ays-quiz-timer{                color: #515151;            }                        \/* Quiz buttons *\/            #ays-quiz-container-10 input#ays-submit,            #ays-quiz-container-10 #ays_finish_quiz_10 .action-button {                background-color: #92be56;                color:#515151;                font-size: 20px;                padding: 10px 20px;                border-radius: 3px;                white-space: nowrap;            }            #ays-quiz-container-10 #ays_finish_quiz_10 .action-button.ays_check_answer {                padding: 5px 10px;            }            #ays-quiz-container-10 #ays_finish_quiz_10 .action-button.ays_download_certificate {                white-space: nowrap;                padding: 5px 10px;            }            #ays-quiz-container-10 #ays_finish_quiz_10 .action-button.ays_arrow {                color:#515151!important;                white-space: nowrap;                padding: 5px 10px;            }            #ays-quiz-container-10 input#ays-submit:hover,            #ays-quiz-container-10 input#ays-submit:focus,            #ays-quiz-container-10 #ays_finish_quiz_10 .action-button:hover,            #ays-quiz-container-10 #ays_finish_quiz_10 .action-button:focus {                box-shadow: 0 0 0 2px #515151;                background-color: #92be56;            }            #ays-quiz-container-10 .ays_restart_button {                color: #515151;            }            #ays-quiz-container-10 .ays_buttons_div {                justify-content: center;            }            #ays-quiz-container-10 .step:first-of-type .ays_buttons_div {                justify-content: center !important;            }            #ays-quiz-container-10 input[type='button'],            #ays-quiz-container-10 input[type='submit'] {                color: #515151 !important;                outline: none;            }            #ays-quiz-container-10 i.ays_early_finish.action-button[disabled]:hover,            #ays-quiz-container-10 i.ays_early_finish.action-button[disabled]:focus,            #ays-quiz-container-10 i.ays_early_finish.action-button[disabled],            #ays-quiz-container-10 i.ays_arrow.action-button[disabled]:hover,            #ays-quiz-container-10 i.ays_arrow.action-button[disabled]:focus,            #ays-quiz-container-10 i.ays_arrow.action-button[disabled] {                color: #aaa !important;            }            \/* Question answers *\/            #ays-quiz-container-10 .ays-field {                border-color: #444;                border-style: solid;                border-width: 1px;                box-shadow: none;flex-direction: row-reverse;            }            #ays-quiz-container-10 .ays-quiz-answers .ays-field:hover{                opacity: 1;            }            #ays-quiz-container-10 #ays_finish_quiz_10 .ays-field label.ays_answer_caption[for^='ays-answer-'] {                z-index: 1;                position:initial;bottom:0;}            #ays-quiz-container-10 #ays_finish_quiz_10 .ays-field input~label[for^='ays-answer-'] {                padding: 10px;            }            #ays-quiz-container-10 #ays_finish_quiz_10 .ays-field.ays_grid_view_item {                width: calc(50% - 5px);                margin-bottom: 10px;            }            #ays-quiz-container-10 #ays_finish_quiz_10 .ays-field.ays_grid_view_item:nth-child(odd) {                margin-right: 5px;            }            #ays-quiz-container-10 #ays_finish_quiz_10 .ays-field input:checked+label:before {                border-color: #92be56;                background: #92be56;                background-clip: content-box;            }            #ays-quiz-container-10 .ays-quiz-answers div.ays-text-right-answer {                color: #515151;            }                        \/* Questions answer image *\/            #ays-quiz-container-10 .ays-answer-image {                width:15em;                height:150px;                object-fit: cover;            }                        \/* Questions answer right\/wrong icons *\/            #ays-quiz-container-10 .ays-field input~label.answered.correct:after{                content: url('https:\/\/gotterfahren.info\/wp-content\/plugins\/quiz-maker\/public\/images\/correct-style-4.png');            }            #ays-quiz-container-10 .ays-field input~label.answered.wrong:after{                content: url('https:\/\/gotterfahren.info\/wp-content\/plugins\/quiz-maker\/public\/images\/wrong-style-4.png');            }            #ays-quiz-container-10 .ays-field label.answered:last-of-type:after{                height: auto;                left: 15px;top: 15px;}            \/* Dropdown questions *\/                        #ays-quiz-container-10 #ays_finish_quiz_10 .ays-field .select2-container--default .select2-selection--single {                border-bottom: 2px solid #92be56;            }                        #ays-quiz-container-10 .ays-field .select2-container--default .select2-selection--single .select2-selection__rendered,            #ays-quiz-container-10 .ays-field .select2-container--default .select2-selection--single .select2-selection__arrow {                color: #515151;            }            #ays-quiz-container-10 .ays-field .select2-container--default .select2-selection--single .select2-selection__rendered,            #ays-quiz-container-10 .select2-container--default .select2-results__option--highlighted[aria-selected] {                background-color: #92be56;            }                        \/* Dropdown questions scroll bar *\/            #ays-quiz-container-10 .select2-results__options::-webkit-scrollbar {                width: 7px            }            #ays-quiz-container-10 .select2-results__options::-webkit-scrollbar-track {                background-color: rgba(255,255,255,0.35);            }            #ays-quiz-container-10 .select2-results__options::-webkit-scrollbar-thumb {                transition: .3s ease-in-out;                background-color: rgba(255,255,255,0.55);            }            #ays-quiz-container-10 .select2-results__options::-webkit-scrollbar-thumb:hover {                transition: .3s ease-in-out;                background-color: rgba(255,255,255,0.85);            }                        \/* WooCommerce product *\/            #ays-quiz-container-10 .ays-woo-block {                background-color: #92be56;            }            #ays-quiz-container-10 .ays-woo-product-block h4.ays-woo-product-title > a {                color: #515151;            }            @media screen and (max-width: 768px){                #ays-quiz-container-10{                    max-width: 100%;                }            }                                    \/* Custom css styles *\/                                    \/* RTL direction styles *\/                    <\/style>            <style>                #ays-quiz-container-10 p {                    margin: 0.625em;                }                                #ays-quiz-container-10 .ays-field.checked_answer_div input:checked~label {                    background-color: rgba(146,190,86,0.6);                }                #ays-quiz-container-10 .ays-field:hover{                    background: rgba(146,190,86,0.8);                    color: #fff;                    transition: all .3s;                }                                #ays-quiz-container-10 #ays_finish_quiz_10 .action-button:hover,                #ays-quiz-container-10 #ays_finish_quiz_10 .action-button:focus {                    box-shadow: 0 0 0 2px rgba(255, 255, 255, 0.5), 0 0 0 3px #515151;                    background: #92be56;                }            <\/style><script>                if(typeof aysQuizOptions === 'undefined'){                    var aysQuizOptions = [];                }                aysQuizOptions['10']  = 'eyJjb2xvciI6IiM5MmJlNTYiLCJiZ19jb2xvciI6IiNmZmYiLCJ0ZXh0X2NvbG9yIjoiIzUxNTE1MSIsImhlaWdodCI6NTAwLCJ3aWR0aCI6MCwiZW5hYmxlX2xvZ2dlZF91c2VycyI6Im9mZiIsImluZm9ybWF0aW9uX2Zvcm0iOiJkaXNhYmxlIiwiZm9ybV9uYW1lIjoib2ZmIiwiZm9ybV9lbWFpbCI6Im9mZiIsImZvcm1fcGhvbmUiOiJvZmYiLCJpbWFnZV93aWR0aCI6IiIsImltYWdlX2hlaWdodCI6IiIsImVuYWJsZV9jb3JyZWN0aW9uIjoib2ZmIiwiZW5hYmxlX3Byb2dyZXNzX2JhciI6Im9uIiwiZW5hYmxlX3F1ZXN0aW9uc19yZXN1bHQiOiJvbiIsInJhbmRvbWl6ZV9xdWVzdGlvbnMiOiJvZmYiLCJyYW5kb21pemVfYW5zd2VycyI6Im9mZiIsImVuYWJsZV9xdWVzdGlvbnNfY291bnRlciI6Im9uIiwiZW5hYmxlX3Jlc3RyaWN0aW9uX3Bhc3MiOiJvZmYiLCJlbmFibGVfcmVzdHJpY3Rpb25fcGFzc191c2VycyI6Im9mZiIsInJlc3RyaWN0aW9uX3Bhc3NfbWVzc2FnZSI6IiIsInJlc3RyaWN0aW9uX3Bhc3NfdXNlcnNfbWVzc2FnZSI6IiIsInVzZXJfcm9sZSI6W10sImF5c191c2Vyc19zZWFyY2giOltdLCJjdXN0b21fY3NzIjoiIiwibGltaXRfdXNlcnMiOiJvZmYiLCJsaW1pdGF0aW9uX21lc3NhZ2UiOiIiLCJyZWRpcmVjdF91cmwiOiIiLCJyZWRpcmVjdGlvbl9kZWxheSI6MCwiYW5zd2Vyc192aWV3IjoibGlzdCIsImVuYWJsZV9ydGxfZGlyZWN0aW9uIjoib2ZmIiwiZW5hYmxlX2xvZ2dlZF91c2Vyc19tZXNzYWdlIjoiPHA+WW91IG5lZWQgdG8gbG9nIGluIHRvIHBhc3MgdGhpcyBxdWl6LjxcL3A+XHJcbiIsInF1ZXN0aW9uc19jb3VudCI6IiIsImVuYWJsZV9xdWVzdGlvbl9iYW5rIjoib2ZmIiwiZW5hYmxlX2xpdmVfcHJvZ3Jlc3NfYmFyIjoib24iLCJlbmFibGVfcGVyY2VudF92aWV3Ijoib2ZmIiwiZW5hYmxlX2F2ZXJhZ2Vfc3RhdGlzdGljYWwiOiJvbiIsImVuYWJsZV9uZXh0X2J1dHRvbiI6Im9uIiwiZW5hYmxlX3ByZXZpb3VzX2J1dHRvbiI6Im9mZiIsImVuYWJsZV9hcnJvd3MiOiJvZmYiLCJ0aW1lcl90ZXh0IjoiIiwicXVpel90aGVtZSI6ImNsYXNzaWNfbGlnaHQiLCJlbmFibGVfc29jaWFsX2J1dHRvbnMiOiJvbiIsImZpbmFsX3Jlc3VsdF90ZXh0IjoiIiwiZW5hYmxlX3Bhc3NfY291bnQiOiJvZmYiLCJoaWRlX3Njb3JlIjoib2ZmIiwicmF0ZV9mb3JtX3RpdGxlIjoiIiwiYm94X3NoYWRvd19jb2xvciI6IiNiYWJhYmEiLCJxdWl6X2JvcmRlcl9yYWRpdXMiOiIwIiwicXVpel9iZ19pbWFnZSI6Imh0dHBzOlwvXC9nb3R0ZXJmYWhyZW4uaW5mb1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDZcLzEzX3F1aXpfMi5qcGciLCJxdWl6X2JvcmRlcl93aWR0aCI6IjEiLCJxdWl6X2JvcmRlcl9zdHlsZSI6InNvbGlkIiwicXVpel9ib3JkZXJfY29sb3IiOiIjMDAwIiwicXVpel9sb2FkZXIiOiJkZWZhdWx0IiwicXVlc3RfYW5pbWF0aW9uIjoic2hha2UiLCJlbmFibGVfYmdfbXVzaWMiOiJvZmYiLCJxdWl6X2JnX211c2ljIjoiIiwiYW5zd2Vyc19mb250X3NpemUiOiIxNSIsInNob3dfY3JlYXRlX2RhdGUiOiJvZmYiLCJzaG93X2F1dGhvciI6Im9mZiIsImVuYWJsZV9lYXJseV9maW5pc2giOiJvZmYiLCJhbnN3ZXJzX3J3X3RleHRzIjoib25fcmVzdWx0c19wYWdlIiwiZGlzYWJsZV9zdG9yZV9kYXRhIjoib2ZmIiwiZW5hYmxlX2JhY2tncm91bmRfZ3JhZGllbnQiOiJvZmYiLCJiYWNrZ3JvdW5kX2dyYWRpZW50X2NvbG9yXzEiOiIjMDAwIiwiYmFja2dyb3VuZF9ncmFkaWVudF9jb2xvcl8yIjoiI2ZmZiIsInF1aXpfZ3JhZGllbnRfZGlyZWN0aW9uIjoidmVydGljYWwiLCJyZWRpcmVjdF9hZnRlcl9zdWJtaXQiOiJvZmYiLCJzdWJtaXRfcmVkaXJlY3RfdXJsIjoiIiwic3VibWl0X3JlZGlyZWN0X2RlbGF5IjowLCJwcm9ncmVzc19iYXJfc3R5bGUiOiJmaXJzdCIsImVuYWJsZV9leGl0X2J1dHRvbiI6Im9mZiIsImV4aXRfcmVkaXJlY3RfdXJsIjoiIiwiaW1hZ2Vfc2l6aW5nIjoiY292ZXIiLCJxdWl6X2JnX2ltYWdlX3Bvc2l0aW9uIjoiY2VudGVyIGNlbnRlciIsImN1c3RvbV9jbGFzcyI6IiIsImVuYWJsZV9zb2NpYWxfbGlua3MiOiJvZmYiLCJzb2NpYWxfbGlua3MiOnsibGlua2VkaW5fbGluayI6IiIsImZhY2Vib29rX2xpbmsiOiIiLCJ0d2l0dGVyX2xpbmsiOiIifSwic2hvd19xdWl6X3RpdGxlIjoib24iLCJzaG93X3F1aXpfZGVzYyI6Im9uIiwic2hvd19sb2dpbl9mb3JtIjoib2ZmIiwibW9iaWxlX21heF93aWR0aCI6IiIsImxpbWl0X3VzZXJzX2J5IjoiaXAiLCJleHBsYW5hdGlvbl90aW1lIjoiNCIsImVuYWJsZV9jbGVhcl9hbnN3ZXIiOiJvZmYiLCJzaG93X2NhdGVnb3J5Ijoib2ZmIiwic2hvd19xdWVzdGlvbl9jYXRlZ29yeSI6Im9mZiIsImFuc3dlcnNfcGFkZGluZyI6IjEwIiwiYW5zd2Vyc19ib3JkZXIiOiJvbiIsImFuc3dlcnNfYm9yZGVyX3dpZHRoIjoiMSIsImFuc3dlcnNfYm9yZGVyX3N0eWxlIjoic29saWQiLCJhbnN3ZXJzX2JvcmRlcl9jb2xvciI6IiM0NDQiLCJhbnNfaW1nX2hlaWdodCI6IjE1MCIsImFuc19pbWdfY2FwdGlvbl9zdHlsZSI6Im91dHNpZGUiLCJhbnNfaW1nX2NhcHRpb25fcG9zaXRpb24iOiJib3R0b20iLCJhbnN3ZXJzX2JveF9zaGFkb3ciOiJvZmYiLCJhbnN3ZXJzX2JveF9zaGFkb3dfY29sb3IiOiIjMDAwIiwic2hvd19hbnN3ZXJzX2NhcHRpb24iOiJvbiIsImFuc3dlcnNfbWFyZ2luIjoiMTAiLCJhbnNfcmlnaHRfd3JvbmdfaWNvbiI6InN0eWxlLTQiLCJkaXNwbGF5X3Njb3JlIjoiYnlfcGVyY2VudGFnZSIsImVuYWJsZV9yd19hc253ZXJzX3NvdW5kcyI6Im9mZiIsInF1aXpfYmdfaW1nX2luX2ZpbmlzaF9wYWdlIjoib24iLCJmaW5pc2hfYWZ0ZXJfd3JvbmdfYW5zd2VyIjoib2ZmIiwiYWZ0ZXJfdGltZXJfdGV4dCI6IiIsImVuYWJsZV9lbnRlcl9rZXkiOiJvbiIsInNob3dfcmF0ZV9hZnRlcl9yYXRlIjoib24iLCJidXR0b25zX3RleHRfY29sb3IiOiIjNTE1MTUxIiwiYnV0dG9uc19wb3NpdGlvbiI6ImNlbnRlciIsImJ1dHRvbnNfc2l6ZSI6Im1lZGl1bSIsImJ1dHRvbnNfZm9udF9zaXplIjoiMjAiLCJidXR0b25zX2xlZnRfcmlnaHRfcGFkZGluZyI6IjIwIiwiYnV0dG9uc190b3BfYm90dG9tX3BhZGRpbmciOiIxMCIsImJ1dHRvbnNfYm9yZGVyX3JhZGl1cyI6IjMiLCJlbmFibGVfYXVkaW9fYXV0b3BsYXkiOiJvZmYiLCJlbmFibGVfbGVhdmVfcGFnZSI6Im9uIiwic2hvd19vbmx5X3dyb25nX2Fuc3dlciI6Im9mZiIsInBhc3Nfc2NvcmUiOjAsInBhc3Nfc2NvcmVfbWVzc2FnZSI6IjxoNCBzdHlsZT1cInRleHQtYWxpZ246IGNlbnRlcjtcIj5Db25ncmF0dWxhdGlvbnMhPFwvaDQ+XHJcbjxwIHN0eWxlPVwidGV4dC1hbGlnbjogY2VudGVyO1wiPllvdSBwYXNzZWQgdGhlIHF1aXohPFwvcD4iLCJmYWlsX3Njb3JlX21lc3NhZ2UiOiI8aDQgc3R5bGU9XCJ0ZXh0LWFsaWduOiBjZW50ZXI7XCI+T29wcyE8XC9oND5cclxuPHAgc3R5bGU9XCJ0ZXh0LWFsaWduOiBjZW50ZXI7XCI+WW91IGFyZSBub3QgcGFzc2VkIHRoZSBxdWl6IVxyXG5UcnkgYWdhaW4hPFwvcD4iLCJhbnN3ZXJzX29iamVjdF9maXQiOiJjb3ZlciIsInF1aXpfbWF4X3Bhc3NfY291bnQiOjEsInF1ZXN0aW9uX2ZvbnRfc2l6ZSI6MTYsInF1aXpfd2lkdGhfYnlfcGVyY2VudGFnZV9weCI6InBpeGVscyIsInF1ZXN0aW9uc19oaW50X2ljb25fb3JfdGV4dCI6ImRlZmF1bHQiLCJxdWVzdGlvbnNfaGludF92YWx1ZSI6IiIsInF1ZXN0aW9uX2NvdW50X3Blcl9wYWdlIjpudWxsLCJxdWVzdGlvbl9jb3VudF9wZXJfcGFnZV9udW1iZXIiOiIiLCJtYWlsX21lc3NhZ2UiOiIiLCJlbmFibGVfY2VydGlmaWNhdGUiOiJvZmYiLCJjZXJ0aWZpY2F0ZV9wYXNzIjoiMCIsImZvcm1fdGl0bGUiOiIiLCJjZXJ0aWZpY2F0ZV90aXRsZSI6IjxwPjxzcGFuIHN0eWxlPVwiZm9udC1zaXplOiA1MHB4OyBmb250LXdlaWdodDogYm9sZDtcIj5DZXJ0aWZpY2F0ZSBvZiBDb21wbGV0aW9uPFwvc3Bhbj48XC9wPlxyXG4iLCJjZXJ0aWZpY2F0ZV9ib2R5IjoiPHA+PHNwYW4gc3R5bGU9XCJmb250LXNpemU6IDI1cHg7XCI+PGk+VGhpcyBpcyB0byBjZXJ0aWZ5IHRoYXQ8XC9pPjxcL3NwYW4+PFwvcD5cclxuPHA+PHNwYW4gc3R5bGU9XCJmb250LXNpemU6IDMwcHg7XCI+PGI+JSV1c2VyX25hbWUlJTxcL2I+PFwvc3Bhbj48XC9wPlxyXG48cD48c3BhbiBzdHlsZT1cImZvbnQtc2l6ZTogMjVweDtcIj48aT5oYXMgY29tcGxldGVkIHRoZSBxdWl6PFwvaT48XC9zcGFuPjxcL3A+XHJcbjxwPjxzcGFuIHN0eWxlPVwiZm9udC1zaXplOiAzMHB4O1wiPlwiJSVxdWl6X25hbWUlJVwiPFwvc3Bhbj48XC9wPlxyXG48cD48c3BhbiBzdHlsZT1cImZvbnQtc2l6ZTogMjBweDtcIj53aXRoIGEgc2NvcmUgb2YgPGI+JSVzY29yZSUlPFwvYj48XC9zcGFuPjxcL3A+XHJcbjxwPjxzcGFuIHN0eWxlPVwiZm9udC1zaXplOiAyNXB4O1wiPjxpPmRhdGVkPFwvaT48XC9zcGFuPjxiciBcLz5cclxuPHNwYW4gc3R5bGU9XCJmb250LXNpemU6IDMwcHg7XCI+JSVjdXJyZW50X2RhdGUlJTxcL3NwYW4+PFwvcD5cclxuIiwibWFpbGNoaW1wX2xpc3QiOiIiLCJhY3RpdmVfZGF0ZV9jaGVjayI6Im9mZiIsImFjdGl2ZUludGVydmFsIjoiMjAyMy0wOC0xOCAwNzo0MToxNiIsImRlYWN0aXZlSW50ZXJ2YWwiOiIyMDIzLTA4LTE4IDA3OjQxOjE2IiwiYWN0aXZlX2RhdGVfbWVzc2FnZSI6IlRoZSBxdWl6IGhhcyBleHBpcmVkISIsImFjdGl2ZV9kYXRlX3ByZV9zdGFydF9tZXNzYWdlIjoiVGhlIHF1aXogd2lsbCBiZSBhdmFpbGFibGUgc29vbiEiLCJjaGVja2JveF9zY29yZV9ieSI6Im9uIiwiY2FsY3VsYXRlX3Njb3JlIjoiYnlfY29ycmVjdG5lc3MiLCJzZW5kX3Jlc3VsdHNfdXNlciI6Im9mZiIsInNlbmRfaW50ZXJ2YWxfbXNnIjoib2ZmIiwicXVlc3Rpb25fYmFua190eXBlIjoiZ2VuZXJhbCIsInF1ZXN0aW9uc19iYW5rX2NhdF9jb3VudCI6eyIxMCI6IiIsIjkiOiIifSwiZW5hYmxlX3RhY2tlcnNfY291bnQiOiJvZmYiLCJ0YWNrZXJzX2NvdW50IjoiIiwic2VuZF9yZXN1bHRzX2FkbWluIjoib24iLCJzZW5kX2ludGVydmFsX21zZ190b19hZG1pbiI6Im9mZiIsInNob3dfaW50ZXJ2YWxfbWVzc2FnZSI6Im9uIiwiYWxsb3dfY29sbGVjdGluZ19sb2dnZWRfaW5fdXNlcnNfZGF0YSI6Im9mZiIsInF1aXpfcGFzc19zY29yZSI6IjAiLCJzZW5kX2NlcnRpZmljYXRlX3RvX2FkbWluIjoib2ZmIiwiY2VydGlmaWNhdGVfaW1hZ2UiOiIiLCJjZXJ0aWZpY2F0ZV9mcmFtZSI6ImRlZmF1bHQiLCJjZXJ0aWZpY2F0ZV9vcmllbnRhdGlvbiI6ImwiLCJtYWtlX3F1ZXN0aW9uc19yZXF1aXJlZCI6Im9mZiIsImVuYWJsZV9wYXNzd29yZCI6Im9mZiIsInBhc3N3b3JkX3F1aXoiOiIiLCJtYWlsX21lc3NhZ2VfYWRtaW4iOiIiLCJzZW5kX21haWxfdG9fc2l0ZV9hZG1pbiI6Im9uIiwicGF5cGFsX2Ftb3VudCI6bnVsbCwicGF5cGFsX2N1cnJlbmN5IjpudWxsLCJlbmFibGVfbW9uaXRvciI6Im9mZiIsIm1vbml0b3JfbGlzdCI6IiIsImFjdGl2ZV9jYW1wX2xpc3QiOiIiLCJlbmFibGVfc2xhY2siOiJvZmYiLCJzbGFja19jb252ZXJzYXRpb24iOiIiLCJhY3RpdmVfY2FtcF9hdXRvbWF0aW9uIjoiIiwiZW5hYmxlX2FjdGl2ZV9jYW1wIjoib2ZmIiwiZW5hYmxlX3phcGllciI6Im9mZiIsInF1aXpfYXR0cmlidXRlcyI6bnVsbCwicXVpel9hdHRyaWJ1dGVzX2FjdGl2ZV9vcmRlciI6bnVsbCwicXVpel9hdHRyaWJ1dGVzX3Bhc3NpdmVfb3JkZXIiOlsiYXlzX2Zvcm1fbmFtZSIsImF5c19mb3JtX2VtYWlsIiwiYXlzX2Zvcm1fcGhvbmUiXSwicmVxdWlyZWRfZmllbGRzIjpudWxsLCJlbmFibGVfdGltZXIiOiJvZmYiLCJ0aW1lciI6MTAwLCJlbmFibGVfcXVpel9yYXRlIjoib2ZmIiwiZW5hYmxlX3JhdGVfYXZnIjoib2ZmIiwiZW5hYmxlX2JveF9zaGFkb3ciOiJvbiIsImVuYWJsZV9ib3JkZXIiOiJvZmYiLCJxdWl6X3RpbWVyX2luX3RpdGxlIjoib2ZmIiwiZW5hYmxlX3JhdGVfY29tbWVudHMiOiJvZmYiLCJlbmFibGVfcmVzdGFydF9idXR0b24iOiJvbiIsImF1dG9maWxsX3VzZXJfZGF0YSI6Im9mZiIsImVuYWJsZV9jb3B5X3Byb3RlY3Rpb24iOiJvZmYiLCJlbmFibGVfcGF5cGFsIjoib2ZmIiwiZW5hYmxlX21haWxjaGltcCI6Im9mZiIsImF5c19lbmFibGVfcmVzdHJpY3Rpb25fcGFzcyI6Im9mZiIsImF5c19lbmFibGVfcmVzdHJpY3Rpb25fcGFzc191c2VycyI6Im9mZiIsInJlc3VsdF90ZXh0IjpudWxsLCJlbmFibGVfcmVzdWx0Ijoib2ZmIiwic3VibWl0X3JlZGlyZWN0X2FmdGVyIjoiIiwicndfYW5zd2Vyc19zb3VuZHMiOmZhbHNlLCJpZCI6IjEwIiwiYXV0aG9yX2lkIjoiMCIsInBvc3RfaWQiOm51bGwsInRpdGxlIjoiR290dGVzIGtvc3Rlbmxvc2VyIEdlc3VuZGhlaXRzcGxhbiIsImRlc2NyaXB0aW9uIjoiIiwicXVpel9pbWFnZSI6IiIsInF1aXpfY2F0ZWdvcnlfaWQiOiIxIiwicXVlc3Rpb25faWRzIjoiMTI4LDEyNywxMjYsMTI1LDEyNCwxMjMsMTI5LDEzMCwxMzEsMTMyLDEzMywxMzQiLCJvcmRlcmluZyI6IjEwIiwicHVibGlzaGVkIjoiMSIsImNyZWF0ZV9kYXRlIjoiMDAwMC0wMC0wMCAwMDowMDowMCIsImludGVydmFscyI6Ilt7XCJpbnRlcnZhbF9taW5cIjpcIjBcIixcImludGVydmFsX21heFwiOlwiMjVcIixcImludGVydmFsX3RleHRcIjpcIlwiLFwiaW50ZXJ2YWxfaW1hZ2VcIjpcIlwiLFwiaW50ZXJ2YWxfd3Byb2R1Y3RcIjowfSx7XCJpbnRlcnZhbF9taW5cIjpcIjI2XCIsXCJpbnRlcnZhbF9tYXhcIjpcIjUwXCIsXCJpbnRlcnZhbF90ZXh0XCI6XCJcIixcImludGVydmFsX2ltYWdlXCI6XCJcIixcImludGVydmFsX3dwcm9kdWN0XCI6MH0se1wiaW50ZXJ2YWxfbWluXCI6XCI1MVwiLFwiaW50ZXJ2YWxfbWF4XCI6XCI3NVwiLFwiaW50ZXJ2YWxfdGV4dFwiOlwiXCIsXCJpbnRlcnZhbF9pbWFnZVwiOlwiXCIsXCJpbnRlcnZhbF93cHJvZHVjdFwiOjB9LHtcImludGVydmFsX21pblwiOlwiNzZcIixcImludGVydmFsX21heFwiOlwiMTAwXCIsXCJpbnRlcnZhbF90ZXh0XCI6XCJcIixcImludGVydmFsX2ltYWdlXCI6XCJcIixcImludGVydmFsX3dwcm9kdWN0XCI6MH1dIn0=';        <\/script>                    <input type='hidden' name='quiz_id' value='10'\/>                    <input type='hidden' name='start_date' class='ays-start-date'\/>                    <input type='hidden' name='ays_finish_quiz_nonce_10' value='c6ed4c7478'\/>                <\/form><\/div>                                <\/div><\/div>\n<h1>DAS K\u00d6NNTE DICH AUCH INTERESSIEREN<\/h1>\n<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/03\/bzg-interesse-stadt.jpg\" alt=\"\"><\/p>\n<h5>Was ist Lebenserfolg?<\/h5>\n<p><a href=\"\/beziehung-zu-gott\/was-ist-lebenserfolg\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/03\/bzg-interesse-bibel.jpg\" alt=\"\"><\/p>\n<h5>Was ist das Hauptanliegen der Bibel?<\/h5>\n<p><a href=\"\/beziehung-zu-gott\/was-ist-das-hauptanliegen-der-bibel\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/03\/bzg-interesse-herz.jpg\" alt=\"\"><\/p>\n<h5>Sinnbilder der Liebe Gottes<\/h5>\n<p><a href=\"\/wege-zum-ziel\/sinnbilder-der-liebe-gottes\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/03\/bzg-interesse-kreuz.jpg\" alt=\"\"><\/p>\n<h5>Jesus von Nazareth<\/h5>\n<p><a href=\"\/beziehung-zu-gott\/jesus-einzigartig-und-unvergleichlich\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/03\/bzg-interesse-taube.jpg\" alt=\"\"><\/p>\n<h5>Leben in der Kraft Gottes<\/h5>\n<p><a href=\"\/beziehung-zu-gott\/leben-in-der-kraft-gottes\"><\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/03\/bzg-interesse-beten.jpg\" alt=\"\"><\/p>\n<h5>Ich will Gott erleben<\/h5>\n<p><a href=\"\/zweifel-oder-glaube\/ich-will-gott-erleben\"><\/a><\/p>\n<\/li>\n<\/ul>\n<p><!--more--><br \/>\n<!-- {\"name\":\"Bibel Antwort Article\",\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"class\":\"banner-normal\",\"image\":\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-banner_13.jpg\",\"image_position\":\"center-center\",\"image_size\":\"cover\",\"padding\":\"xlarge\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"}}]}],\"name\":\"Banner\",\"modified\":\"2021-03-23T16:02:54.885Z\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding_remove_top\":false,\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"breadcrumbs\",\"props\":{\"home_text\":\"GOTT ERFAHREN\",\"show_current\":true,\"show_home\":true,\"visibility\":\"s\"}}]}]},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Gottes kostenloser Gesundheitsplan\",\"margin_remove_bottom\":true,\"title_element\":\"h1\",\"title_style\":\"h2\"}}]}],\"props\":{\"margin\":\"default\"}},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Gute medizinische Versorgung ist unbezahlbar \\u2013 doch w\\u00e4re es nicht besser, wenn wir keine \\u00c4rzte mehr ben\\u00f6tigten? Wussten Sie, dass es einen bew\\u00e4hrten Weg gibt, um viele \\u00c4rzte arbeitslos zu machen? Tragen Sie Sorge zu Ihrem K\\u00f6rper! Wissenschaftler warnen un\\u00fcberh\\u00f6rbar vor hohem Cholesterin, Tabak, Stress, \\u00dcbergewicht und Alkohol. Warum also Ihr Gl\\u00fcck aufs Spiel setzen? Spit\\u00e4ler und psychiatrische Institutionen sind \\u00fcberf\\u00fcllt von solchen, welche diese Warnungen missachtet haben. M\\u00f6chten Sie wirklich zu jenen geh\\u00f6ren? Gott sorgt sich tats\\u00e4chlich, wie Sie mit Ihrem K\\u00f6rper umgehen. Er bietet Ihnen einen kostenlosen Gesundheitsplan samt Gebrauchsanleitung an\\u2026 die Bibel! Entdecken Sie in dieser Studienanleitung die erstaunlichen Fakten, wie Sie sich einer guten Gesundheit und eines langen Lebens erfreuen k\\u00f6nnen. Bitte lesen Sie aber erst alles ganz aufmerksam, ehe Sie voreilige Schl\\u00fcsse ziehen!<\\\/p>\",\"margin\":\"default\"}}]}]},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"accordion\",\"props\":{\"collapsible\":false,\"content_column_breakpoint\":\"m\",\"css\":\"p strong{color: #92be56!important;}\",\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"link_text\":\"\",\"multiple\":true,\"show_image\":true,\"show_link\":true},\"children\":[{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_rechts size-thumbnail wp-image-10176 alignright\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q1-BibleReading-AfricanMan-BlueShirt-150x150.jpg\\\" alt=\\\"1. Sind die Gesundheitsprinzipien tats\\u00e4chlich Teil der biblischen Religion?\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/> <em>\\u201cMein Lieber, ich w\\u00fcnsche dir in allen Dingen Wohlergehen und Gesundheit, so wie es deiner Seele wohlgeht!\\u201d 3.Johannes 2<\\\/em><\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>Antwort:<\\\/strong> Ja. Tats\\u00e4chlich erw\\u00e4hnt die Bibel die Wichtigkeit der Gesundheit beinahe an erster Stelle. Unser Verstand und unser geistliches Leben und der Leib stehen in enger Beziehung zueinander. Was den einen Teil betrifft, beeinflusst auch die andern. Wenn unser K\\u00f6rper \\u00fcberfordert wird, kann unser Verstand und unser geistliches Leben sich nicht nach Gottes Plan entfalten.<\\\/p>\",\"title\":\"1. Sind die Gesundheitsprinzipien tats\\u00e4chlich Teil der biblischen Religion?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"<em>\\u201d Und der HERR hat uns geboten, alle diese Satzungen zu halten,\\u2026 und es uns gut geht alle Tage und er uns am Leben erh\\u00e4lt, wie es heute der Fall ist.\\u201d 5.Mose 6:24 \\u201cUnd ihr sollt dem HERRN, eurem Gott, dienen, so wird er dein Brot und dein Wasser segnen; und ich will die Krankheit aus deiner Mitte hinweg nehmen.\\u201d 2.Mose 23:25<\\\/em>\n\n<p><\\\/p>\\n\n\n<p><strong>Antwort:<\\\/strong> Gott gab Gesundheitsgesetze, weil er wei\\u00df, was f\\u00fcr den menschlichen K\\u00f6rper am besten ist. Autohersteller legen bei jedem neuen Fahrzeug eine \\u201cGebrauchsanweisung\\u201d ins Handschuhfach, weil sie wissen, wie ihr Produkt am besten funktioniert. Gott, der unsern K\\u00f6rper geschaffen hat, h\\u00e4lt ebenfalls eine \\u201cGebrauchsanweisung\\u201d daf\\u00fcr bereit. Diese Anweisung wird die Heilige Bibel genannt. Das Missachten dieser Gebrauchsanweisung hat Krankheiten, verwirrtes Denken und ein ausgebranntes Leben zur Folge, genauso wie die falsche Handhabung eines Autos ernsthafte Schwierigkeiten nach sich zieht. Wer sich an Gottes Anweisungen h\\u00e4lt, bewahrt die Gesundheit und erfreut sich eines erf\\u00fcllten Lebens. Gottes gro\\u00dfartige Gesundheitsgesetze sind mit einem Schutzwall zu vergleichen, die uns vor Krankheiten sch\\u00fctzen, durch die Satan uns Leiden zuf\\u00fcgen will. Gott hat uns diese Gesetze gegeben, damit wir die Fallen des Teufels meiden.<\\\/p>\",\"title\":\"2. Warum gab Gott seinem Volk Gesundheitsgesetze?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_rechts size-thumbnail wp-image-10176 alignright\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q3-Woman-WafflesOJ-150x150.jpg\\\" alt=\\\"3. Haben Gottes Gesundheitsgesetze auch mit dem zu tun, was wir essen und trinken?\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/> <em>\\u201cH\\u00f6rt doch auf mich, so sollt ihr Gutes essen,\\u201d Jesaja 55:2 \\u201cOb ihr nun esst oder trinkt oder sonst etwas tut \\u2014 tut alles zur Ehre Gottes!\\u201d 1.Korinther 10:31<\\\/em><\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>Antwort:<\\\/strong> Ja, ein Christ wird sogar anders essen und trinken als andere \\u2013 und das alles zu Gottes Ehre \\u2013 indem er nur das zu sich nimmt, was \\u201cgut\\u201d ist. Wenn Gott sagt, dass gewisse Dinge nicht als Nahrung f\\u00fcr uns geeignet sind, muss er einen guten Grund daf\\u00fcr haben. Er spricht nicht als Diktator, sondern als liebevoller Vater. Alle seine Ratschl\\u00e4ge dienen immer zu unserem besten. Die biblische Verhei\\u00dfung lautet: \\u201c\\u2026wer in Lauterkeit wandelt, dem versagt er nichts Gutes.\\u201d Psalmen 84:12 Enth\\u00e4lt Gott uns etwas vor, dann aus dem einen Grund, weil es uns schaden w\\u00fcrde.<\\\/p>\\n\n\n<p><b>Note:<\\\/b> Kein Mensch kann sich den Himmel durch Essen verdienen. Selbst das Essen von Engelsnahrung wird die Menschen nicht bef\\u00e4higen, ins Paradies einzugehen. Einzig und allein die Annahme Jesu als Herrn und Erl\\u00f6ser vermag dies. Das Missachten von Gottes Gesundheitsgesetzen kann aber dazu f\\u00fchren, dass ein Mensch verloren geht, weil dies sein Unterscheidungsverm\\u00f6gen zerst\\u00f6rt und ihn zum S\\u00fcndigen veranlasst.<\\\/p>\",\"title\":\"3. Haben Gottes Gesundheitsgesetze auch mit dem zu tun, was wir essen und trinken?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_links size-thumbnail wp-image-10176 alignleft\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q4-Fruit-Oat-Bowl-150x150.jpg\\\" alt=\\\"4. Was gab Gott den Menschen als ideale Nahrung zu essen, als er sie schuf?\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/> <em>\\u201cSiehe, ich habe euch alles samentragende Gew\\u00e4chs gegeben, \\u2026auch alle B\\u00e4ume, an denen samentragende Fr\\u00fcchte sind. Sie sollen euch zur Nahrung dienen;\\u201d \\u201cVon jedem Baum des Gartens darfst du nach Belieben essen; aber\\u2026\\u201d 1.Mose 1:29; 2:16<\\\/em><\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>Antwort:<\\\/strong> Zu Beginn gab Gott den Menschen Fr\\u00fcchte, Samen und N\\u00fcsse zu essen. Gem\\u00fcse kam etwas sp\\u00e4ter dazu (1.Mose 3:18).<\\\/p>\",\"title\":\"4. Was gab Gott den Menschen als ideale Nahrung zu essen, als er sie schuf?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_rechts size-thumbnail wp-image-10176 alignright\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q5-UncleanAnimals-150x150.jpg\\\" alt=\\\"5. Welche Dinge werden in der Bibel von Gott ausdr\\u00fccklich als unrein bezeichnet und verboten?\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/><\\\/p>\\n\n\n<p><strong>Antwort:<\\\/strong> In 3.Mose 11 und 5.Mose 14 bezeichnet Gott ganz klar, welche Tierarten unrein sind. Lesen Sie beide Kapitel ganz durch.<\\\/p>\\n\n\n<p><b>A. Alle Tiere, welche die Klauen nicht spalten und nicht wiederk\\u00e4uen<\\\/b> (5.Mose 14:6).<\\\/p>\\n\n\n<p><b>B. Alle Fische und Wassertiere, welche keine Schuppen und keine Flo\\u00dffedern haben.<\\\/b> Fast alle Fische sind rein (5.Mose 14:9).<\\\/p>\\n\n\n<p><b>C. Alle Raubv\\u00f6gel, Aasfresser und Fischverzehrer<\\\/b> (3.Mose 11:13-20).<\\\/p>\\n\n\n<p><b>D. Die meisten \\u201ckriechenden\\u201d (wirbellosen) Tiere sind ebenfalls unrein<\\\/b> (3.Mose 11:21-47).<\\\/p>\\n\n\n<p><b>Anmerkung:<\\\/b> <em>Diese Kapitel machen deutlich, dass die meisten Tiere, V\\u00f6gel und Wassertiere, die gegessen werden, rein sind. Es gibt jedoch einige beachtenswerte Ausnahmen. Nach Gottes Anweisungen sind folgende Tiere unrein und d\\u00fcrfen nicht gegessen werden: Schweine, Eichh\\u00f6rnchen, Kaninchen, Seewolf, Aal, Hummer, Muscheln, Krabben, Crevetten, Austern, Fr\\u00f6sche und viele andere.<\\\/em><\\\/p>\",\"title\":\"5. Welche Dinge werden in der Bibel von Gott ausdr\\u00fccklich als unrein bezeichnet und verboten?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_links size-thumbnail wp-image-10168 alignleft\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q6-Bacon-150x150.jpg\\\" alt=\\\"6. Ich esse aber gerne Schweinefleisch. Wird Gott mich deswegen vernichten?\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/> <em>\\u201cDenn der HERR wird durchs Feuer richten und durch sein Schwert alles Fleisch; und der Get\\u00f6teten des HERRN wird viel sein. Die sich heiligen und reinigen \\u2026 und essen Schweinefleisch, Gr\\u00e4uel und M\\u00e4use, sollen weggerafft werden miteinander, spricht der HERR.\\u201d Jesaja 66:16.17<\\\/em><\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>Antwort:<\\\/strong> Es mag schockieren, doch es ist wahr und muss gesagt werden: Die Bibel erkl\\u00e4rt, dass alle, die \\u201cSchweinefleisch\\u201d, \\u201cM\\u00e4use\\u201d und andere unreine Dinge essen, welche ein \\u201cGr\\u00e4uel\\u201d sind, beim Kommen des Herrn mit Feuer vernichtet werden. Wenn Gott sagt, dass wir gewisse Dinge meiden sollen, dann sollten wir ihm unbedingt gehorchen. Bedenken wir, dass das Essen eines einzigen St\\u00fcckes der verbotenen Frucht von Adam und Eva, einem vormals s\\u00fcndlosen Paar, S\\u00fcnde und Tod in diese Welt brachte. Wie kann man zu sagen wagen, dass dies unwichtig sei, wo Gott doch so klar die damit verbundenen Konsequenzen aufzeigt? Gott sagt, dass Menschen vernichtet werden, weil sie \\u201ctaten, was mir \\u00fcbel gefiel, und erw\\u00e4hlten, was mir nicht gefiel.\\u201d Jesaja 66:4<\\\/p>\",\"title\":\"6. Ich esse aber gerne Schweinefleisch. Wird Gott mich deswegen vernichten?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_rechts size-thumbnail wp-image-10168 alignright\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q7-NoahsArk-150x150.jpg\\\" alt=\\\"7. Hat dieses Gesetz von reinen und unreinen Tieren seinen Ursprung nicht am Sinai? Galt dieses nicht ausschlie\\u00dflich den Juden und endete am Kreuz?\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/> <em>\\u201cUnd der HERR sprach zu Noah: \\u2026 Aus allerlei reinem Vieh nimm zu dir je sieben und sieben, das M\\u00e4nnlein und sein Weiblein; von dem unreinen Vieh aber je ein Paar, das M\\u00e4nnlein und sein Weiblein.\\u201d 1.Mose 7:1.2<\\\/em><\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>Antwort:<\\\/strong> Nein, wirklich nicht! Die Bibel enth\\u00e4lt gen\\u00fcgend Beweise, dass es von Anbeginn der Sch\\u00f6pfung reine und unreine Tiere gab. Noah lebte lange bevor es Juden gab, und doch wusste er um rein und unrein, denn er nahm von den reinen Tieren \\u201csieben\\u201d Paare und von den unreinen nur \\u201ceines\\u201d mit in die Arche. In Offenbarung 18:2 werden gewisse unreine V\\u00f6gel erw\\u00e4hnt zur Zeit kurz vor dem zweiten Kommen Christi. Der Tod Jesu hat diese Gesundheitsgesetze nicht au\\u00dfer Kraft gesetzt, denn die Bibel sagt, dass alle, welche diese Gesetze \\u00fcbertreten, bei Jesu Wiederkunft ausgel\\u00f6scht werden. (Jesaja 66:15-17). Weder der Magen noch das Verdauungssystem der Juden unterscheiden sich von denjenigen der Heiden. Diese Gesundheitsgesetze gelten f\\u00fcr alle Menschen aller Zeiten.<\\\/p>\",\"title\":\"7. Hat dieses Gesetz von reinen und unreinen Tieren seinen Ursprung nicht am Sinai? Galt dieses nicht ausschlie\\u00dflich den Juden und endete am Kreuz?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_links size-thumbnail wp-image-10169 alignleft\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q8-Alcohol-Man-150x150.jpg\\\" alt=\\\"8. Verbietet die Bibel den Gebrauch von alkoholischen Getr\\u00e4nken?\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/> <em>\\u201cDer Wein macht zum Sp\\u00f6tter, das starke Getr\\u00e4nk macht wild, und keiner, der sich damit berauscht, wird weise.\\u201d Spr\\u00fcche 20:1 \\u201cSchau nicht darauf, wie der Wein r\\u00f6tlich schimmert, wie er im Becher perlt! Er gleitet leicht hinunter; zuletzt aber bei\\u00dft er wie eine Schlange und sticht wie eine Otter!\\u201d Spr\\u00fcche 23:31.32 \\u201cWisst ihr denn nicht, dass weder Unz\\u00fcchtige\\u2026noch Trunkenbolde,\\u2026 werden das Reich Gottes erben. 1.Korinther 6:9.10<\\\/em><\\\/p>\\n\n\n<p><strong>Antwort:<\\\/strong> Ja, die Bibel untersagt den Gebrauch von alkoholischen Getr\\u00e4nken.<\\\/p>\",\"title\":\"8. Verbietet die Bibel den Gebrauch von alkoholischen Getr\\u00e4nken?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_rechts size-thumbnail wp-image-10170 alignright\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q9-Cigarettes-Handcuff-150x150.jpg\\\" alt=\\\"9. Verurteilt die Bibel den Gebrauch von Tabak?\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/><\\\/p>\\n\n\n<p><strong>Antwort:<\\\/strong> Ja. Die Bibel nennt sechs Gr\\u00fcnde, warum der Gebrauch von Tabak Gott missf\\u00e4llt:<\\\/p>\\n\n\n<p><b>A. Der Gebrauch von Tabak schadet der Gesundheit und verunreinigt den K\\u00f6rper.<\\\/b><\\\/p>\\n\n\n<p>\\u201d Wisst ihr nicht, dass ihr Gottes Tempel seid, und dass der Geist Gottes in euch wohnt? Wenn jemand den Tempel Gottes verderbt, den wird Gott verderben; denn der Tempel Gottes ist heilig, und der seid ihr.\\u201d 1.Korinther 3:16.17<\\\/p>\\n\n\n<p><b>B. Nikotin ist ein Suchtmittel, das die Menschen versklavt.<\\\/b><\\\/p>\\n\n\n<p>In R\\u00f6mer 6:16 steht, dass wir Knechte dessen oder desjenigen werden, welchem wir anhangen. Wer Tabak gebraucht ist ein Knecht oder Abh\\u00e4ngiger des Nikotins. Jesus sagt: \\u201cDu sollst den Herrn, deinen Gott, anbeten und ihm allein dienen!\\u201d Matth\\u00e4us 4:10<\\\/p>\\n\n\n<p><b>C. Die Tabaksucht ist unrein. <\\\/b><\\\/p>\\n\n\n<p>\\u201cDarum geht hinaus von ihnen und sondert euch ab, spricht der Herr, und r\\u00fchrt nichts Unreines an! Und ich will euch aufnehmen.\\u201d 2.Korinther 6:17 Es ist undenkbar, dass Christus in irgendeiner Form Tabak gebraucht h\\u00e4tte, nicht wahr?<\\\/p>\\n\n\n<p><b>D. Der Gebrauch von Tabak ist Geldverschwendung. <\\\/b><\\\/p>\\n\n\n<p>\\u201cWarum wiegt ihr Geld ab f\\u00fcr das, was kein Brot ist?\\u201d Jesaja 55:2 Wir sind Gottes Verwalter \\u00fcber das uns gegebene Geld, und \\u201c(Es) wird von einem Haushalter nur verlangt, dass er treu erfunden wird.\\u201d 1.Korinther 4:2<\\\/p>\\n\n\n<p><b>E. Der Gebrauch von Tabak bringt niemanden n\\u00e4her zu Christus. <\\\/b><\\\/p>\\n\n\n<p>\\u201cEnthaltet euch der fleischlichen Begierden, die gegen die Seele streiten.\\u201d 1.Petrus 2:11 Der Gebrauch von Tabak ist eine Lust des Fleisches.<\\\/p>\\n\n\n<p><b>F. Der Gebrauch von Tabak verk\\u00fcrzt das Leben. <\\\/b><\\\/p>\\n\n\n<p>Wissenschaftliche Erkenntnisse best\\u00e4tigen die Tatsache, dass der Gebrauch von Tabak die Lebenszeit bis zu einem Drittel verk\\u00fcrzt. Dies ist gegen das Gebot Gottes, das sagt: Du sollst nicht t\\u00f6ten (2.Mose 20:13). Auch wenn es sich dabei um ein langsames T\\u00f6ten handelt, so ist es dennoch T\\u00f6ten. Eines der besten Mittel, Ihr Begr\\u00e4bnis hinauszuschieben ist, den Gebrauch von Tabak aufzugeben.<\\\/p>\",\"title\":\"9. Verurteilt die Bibel den Gebrauch von Tabak?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_links size-thumbnail wp-image-10171 alignleft\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q10-Family-Mealtime-150x150.jpg\\\" alt=\\\"10. Welches sind einige der einfachen, jedoch sehr wichtigen Gesundheitsgesetze, die wir in der Bibel finden?\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/><\\\/p>\\n\n\n<p><strong>Antwort:<\\\/strong> Hier sind 11 biblische Gesundheitsregeln:<\\\/p>\\n\n\n<p><b>A. Nehmen Sie Ihre Mahlzeiten in regelm\\u00e4\\u00dfigen Abst\\u00e4nden ein und verwenden Sie kein tierisches Fett oder Blut. <\\\/b><\\\/p>\\n\n\n<p>\\u201c\\u2026 zur rechten Zeit speisen.\\u201d Prediger 10:17 \\u201cDas ist eine ewige Satzung f\\u00fcr eure [k\\u00fcnftigen] Geschlechter \\u2026 dass ihr weder Fett noch Blut essen sollt.\\u201d 3.Mose 3:17<\\\/p>\\n\n\n<p><b>Anmerkung:<\\\/b> <em>Neue wissenschaftliche Studien haben die Tatsache best\\u00e4tigt, dass die meisten Herzinfarkte auf einen hohen Cholesterinspiegel im Blut zur\\u00fcckzuf\\u00fchren sind, und dass die Verwendung von \\u201cFetten\\u201d diesen erh\\u00f6hten Wert verursacht. Es scheint, dass der Herr wei\\u00df, wovon er spricht, nicht wahr?<\\\/em><\\\/p>\\n\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_rechts size-thumbnail wp-image-10171 alignright\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q10-Overeating-150x150.jpg\\\" alt=\\\"\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/> <b>B. \\u00dcberiss dich nicht. <\\\/b><\\\/p>\\n\n\n<p>\\u201cSetze ein Messer an deine Kehle, wenn du gierig bist.\\u201d Spr\\u00fcche 23:2 In Lukas 21:34 warnt Christus ausdr\\u00fccklich vor \\u201cFresssucht\\u201d (\\u00dcberessen) in den letzten Tagen. Die Gewohnheit des \\u00dcberessens ist die Ursache f\\u00fcr viele Krankheiten.<\\\/p>\\n\n\n<p><b>C. Hege weder Neid noch Groll.<\\\/b><\\\/p>\\n\n\n<p>Diese \\u00dcbel unterbinden K\\u00f6rperfunktionen. Die Bibel sagt, dass der Neid wie \\u201cFra\\u00df in den Gebeinen\\u201d ist. Spr\\u00fcche 14:30 Christus verlangt sogar von uns, dass, wenn andere etwas gegen uns haben, wir dies bereinigen. (Matth\\u00e4us 5:23.24).<\\\/p>\\n\n\n<p><b>D. Hege eine frohe, freudige Einstellung. <\\\/b><\\\/p>\\n\n\n<p>\\u201cEin fr\\u00f6hliches Herz f\\u00f6rdert die Genesung.\\u201d Spr\\u00fcche 17:22 Viele Krankheiten sind auf Depressionen zur\\u00fcckzuf\\u00fchren. Eine frohe, freudige Lebenseinstellung hingegen ist f\\u00fcr die Gesundheit f\\u00f6rderlich und verl\\u00e4ngert das Leben.<\\\/p>\\n\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_links size-thumbnail wp-image-10171 alignleft\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q10-Friends-Women-Hug-150x150.jpg\\\" alt=\\\"\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/><br \\\/><b>E. Vertraue dem Herrn voll und ganz. <\\\/b><\\\/p>\\n\n\n<p>\\u201cDie Furcht des HERRN dient zum Leben; \\u2026 und wird satt bleiben.\\u201d Spr\\u00fcche 19:23 Gottesfurcht st\\u00e4rkt Gesundheit und Leben. \\u201cMein Sohn, achte auf meine Worte. \\u2026 Denn sie sind das Leben denen, die sie finden, und heilsam ihrem ganzen Leib.\\u201d Spr\\u00fcche 4:20-22 Somit ist Gesundheit die Folge von Gehorsam Gottes Geboten gegen\\u00fcber und vollem Vertrauen in ihn.<\\\/p>\\n\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_rechts size-thumbnail wp-image-10171 alignright\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q10-Balanced-ExerciseSleeping-150x150.jpg\\\" alt=\\\"\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/><b>F. Ausgewogenheit zwischen Arbeit, Bewegung, Schlaf und Ruhe. <\\\/b><\\\/p>\\n\n\n<p>\\u201cSechs Tage sollst du arbeiten und alle deine Werke tun; aber am siebten Tag ist der Sabbat des HERRN, deines Gottes; da sollst du kein Werk tun.\\u201d 2.Mose 20:9.10 \\u201cS\\u00fc\\u00df ist der Schlaf des Arbeiters.\\u201d Prediger 5:11 \\u201cIm Schwei\\u00dfe deines Angesichts sollst du (dein) Brot essen. 1.Mose 3:19 \\u201cEs ist umsonst, dass ihr fr\\u00fch aufsteht und sp\\u00e4t aufbleibt.\\u201d Psalmen 127:2 \\u201cDenn was hat der Mensch von all seiner M\\u00fche und dem Trachten seines Herzens, womit er sich abm\\u00fcht unter der Sonne? Denn er plagt sich jeden Tag mit Kummer und \\u00c4rger; sogar in der Nacht hat sein Herz keine Ruhe. Auch das ist nichtig!\\u201d Prediger 2:22.23<\\\/p>\\n\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_links size-thumbnail wp-image-10171 alignleft\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q10-Soda-Coffee-150x150.jpg\\\" alt=\\\"\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/><b>G. Halte deinen K\\u00f6rper rein. \\u201c<\\\/b><\\\/p>\\n\n\n<p>\\u2026 reinigt euch.\\u201d Jesaja 52:11<\\\/p>\\n\n\n<p><b>H. Sei m\\u00e4\\u00dfig in allen Dingen. <\\\/b><\\\/p>\\n\n\n<p>\\u201cJeder aber, der sich am Wettkampf beteiligt, ist enthaltsam in allem.\\u201d 1.Korinther 9:25 Ein Christ wird alles meiden, was sch\\u00e4dlich ist und alles mit M\\u00e4\\u00dfigkeit gebrauchen, was gut ist. Gewohnheiten, welche der Gesundheit schaden, sind eine \\u00dcbertretung des Gesetzes: \\u201cDu sollst nicht t\\u00f6ten.\\u201d Solche Gewohnheiten t\\u00f6ten nach und nach und k\\u00f6nnen als \\u201cSelbstmord auf Raten\\u201d bezeichnet werden.<\\\/p>\\n\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_rechts size-thumbnail wp-image-10171 alignright\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q10-Bread-Loaf-Rip-150x150.jpg\\\" alt=\\\"\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/><b>I. Meide alle sch\\u00e4dlichen Stimulanzien. <\\\/b><\\\/p>\\n\n\n<p>Das mag f\\u00fcr einige eine \\u00dcberraschung sein. Die medizinische Wissenschaft hat die Tatsache best\\u00e4tigt, dass Schwarztee, Kaffee und S\\u00fc\\u00dfgetr\\u00e4nke, welche die s\\u00fcchtig machende Droge Koffein und andere sch\\u00e4dliche Zus\\u00e4tze enthalten, dem menschlichen K\\u00f6rper schaden.<\\\/p>\\n\n\n<p>Keinerlei N\\u00e4hrwert ist darin enthalten, au\\u00dfer dem Zucker oder dem beigef\\u00fcgten Kaffeerahm. Viele von uns verwenden bereits zu viel Zucker. Stimulanzien geben dem K\\u00f6rper einen gef\\u00e4hrlichen, k\\u00fcnstlichen Auftrieb. Die Beliebtheit dieser Getr\\u00e4nke ist nicht ihrem Geschmack oder der Werbung zuzuschreiben, sondern der darin enthaltenen Dosis Koffein. Viele Menschen sind kr\\u00e4nklich wegen ihrer Abh\\u00e4ngigkeit von Kaffee, Schwarztee und S\\u00fc\\u00dfgetr\\u00e4nken, die Koffein enthalten. Doch die wahre Trag\\u00f6die besteht darin, dass M\\u00e4nner und Frauen, die nach Frieden und Kraft suchen, zu Schwarztee und Kaffee greifen, was lediglich ein billiger Ersatz f\\u00fcr Gebet und Bibelstudium ist. Das freut den Teufel und zerst\\u00f6rt das menschliche Leben.<\\\/p>\\n\n\n<p><b>J. Mache die Essenszeit zu einer frohen Zeit. <\\\/b><\\\/p>\\n\n\n<p>\\u201cdoch wenn irgendein Mensch isst und trinkt und Gutes genie\\u00dft bei all seiner M\\u00fche, so ist das auch eine Gabe Gottes.\\u201d Prediger 3:13 Unliebsame Szenen w\\u00e4hrend den Mahlzeiten st\\u00f6ren die Verdauung. Dies sollte vermieden werden.<\\\/p>\\n\n\n<p><b>K. Hilf denen, die in Not sind.<\\\/b><\\\/p>\\n\n\n<p>\\u201cIst nicht das ein Fasten, \\u2026 dass ihr ungerechte Fesseln losmacht, \\u2026 dass ihr die Unterdr\\u00fcckten freilasst \\u2026 dass du dem Hungrigen dein Brot brichst und arme Verfolgte in dein Haus f\\u00fchrst, dass, wenn du einen Entbl\\u00f6\\u00dften siehst, du ihn bekleidest und dich deinem eigenen Fleisch nicht entziehst?\\u201d Jesaja 58:6-8 Dies ist zu klar, um missverstanden zu werden. Wenn wir den Armen und Notleidenden helfen, f\\u00f6rdert das unsere eigene Gesundheit.<\\\/p>\",\"title\":\"10. Welches sind einige der einfachen, jedoch sehr wichtigen Gesundheitsgesetze, die wir in der Bibel finden?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_rechts size-thumbnail wp-image-10171 alignright\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q11-HospitalMan-150x150.jpg\\\" alt=\\\"11. Welche feierliche Ermahnung ergeht an jene, welche Gottes Anweisungen missachten?\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/> <em>\\u201cIrrt euch nicht: Gott l\\u00e4sst sich nicht spotten! Denn was der Mensch s\\u00e4t, das wird er auch ernten.\\u201d Galater 6:7<\\\/em><\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>Antwort:<\\\/strong> Die Antwort ist zu klar, um missverstanden werden zu k\\u00f6nnen. Wer Gottes Gesetze in Bezug auf das Sorgetragen zum Organismus bricht, wird einen kranken K\\u00f6rper und ein ausgebranntes Leben ernten, genauso wie einer, der mit seinem Auto gro\\u00dfe Probleme bekommt, wenn er es falsch behandelt. Wer weiterf\\u00e4hrt, Gottes Gesundheitsgesetze zu \\u00fcbertreten, wird letztlich vernichtet werden (1. Korinther 3:16.17). Gottes Gesundheitsgesetze sind uns nicht aus Willk\\u00fcr gegeben. Es handelt sich um feststehende Naturgesetze des Universums, genauso wie das Gesetz der Schwerkraft. Das Missachten dieser Gesetze hat immer verheerende Folgen. Die Bibel sagt: \\u201c\\u2026 so ist ein unverdienter Fluch: Er trifft nicht ein.\\u201d Spr\\u00fcche 26:2 Schwierigkeiten r\\u00fchren daher, dass man die Gesundheitsgesetze missachtet. Gott in seiner Gnade informiert uns \\u00fcber diese Gesetze, damit wir vor den Folgen der Missachtung seiner Anweisungen bewahrt bleiben.<\\\/p>\",\"title\":\"11. Welche feierliche Ermahnung ergeht an jene, welche Gottes Anweisungen missachten?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_links size-thumbnail wp-image-10171 alignleft\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q12-Grandpa-Girl-Cooking-150x150.jpg\\\" alt=\\\"12. Wie sind unsere Kinder und Gro\\u00dfkinder gesundheitlich in Mitleidenschaft gezogen?\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/> <em>\\u201cDu sollst es nicht essen, damit es dir und deinen Kindern nach dir gut geht.\\u201d 5.Mose 12:25 \\u201cDenn ich, der HERR, dein Gott, bin ein eifers\\u00fcchtiger Gott, der die Schuld der V\\u00e4ter heimsucht an den Kindern bis in das dritte und vierte Glied derer, die mich hassen.\\u201d 2.Mose 20:5<\\\/em><\\\/p>\\n\n\n<p><strong>Antwort:<\\\/strong> Gott sagt ganz klar, dass Kinder und Gro\\u00dfkinder (bis in die vierte Generation) f\\u00fcr die Torheit ihrer Eltern bezahlen, welche Gottes Gesundheitsgesetze missachten. Wenn M\\u00fctter und V\\u00e4ter Gottes Gesundheitsprinzipien f\\u00fcr ihr Leben ablehnen, erben ihre Kinder und Gro\\u00dfkinder geschw\\u00e4chte, kr\\u00e4nkliche K\\u00f6rper. M\\u00f6chten Sie das Ihren Kindern und Gro\\u00dfkindern antun?<\\\/p>\",\"title\":\"12. Wie sind unsere Kinder und Gro\\u00dfkinder gesundheitlich in Mitleidenschaft gezogen?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_rechts size-thumbnail wp-image-10171 alignright\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q13-Bible-ManReading-BrownShirt-150x150.jpg\\\" alt=\\\"13. Welch weitere ern\\u00fcchternde Tatsachen offenbart uns Gottes Wort?\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/> <em>\\u201cUnd es wird niemals jemand in sie hineingehen, der verunreinigt, noch jemand, der Gr\\u00e4uel und L\\u00fcge ver\\u00fcbt.\\u201d Offenbarung 21:27 \\u201cDenen aber, deren Herz ihren Gr\\u00e4ueln und Scheusalen nachwandelt, will ich ihren Wandel auf ihren Kopf vergelten! spricht GOTT, der HER.\\u201d Hesekiel 11:21<\\\/em><\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>Antwort:<\\\/strong> Nichts unreines, fehlerhaftes wird in Gottes Reich Eingang finden. Alle sch\\u00e4dlichen Gewohnheiten verunreinigen einen Menschen. Der Verzehr von ungeeigneter Nahrung verunreinigt (Daniel 1:8). Das ist ern\\u00fcchternd, jedoch wahr. Das Handeln nach eigenem Gutd\\u00fcnken, nach dem, \\u201cwas Gott \\u00fcbel gef\\u00e4llt\\u201d, wird die Menschen ihr ewiges Heil kosten (Jesaja 66:3.4,15-17).<\\\/p>\",\"title\":\"13. Welch weitere ern\\u00fcchternde Tatsachen offenbart uns Gottes Wort?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_links size-thumbnail wp-image-10171 alignleft\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q14-Woman-African-PurpleSweater-150x150.jpg\\\" alt=\\\"14. Was sollte jeder aufrichtige Christ sogleich anstreben?\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/> <em>\\u201cso wollen wir uns reinigen von aller Befleckung des Fleisches und des Geistes.\\u201d 2.Korinther 7:1 \\u201cUnd jeder, der diese Hoffnung auf ihn hat, reinigt sich, gleichwie auch Er rein ist.\\u201d 1.Johannes 3:3. \\u201cLiebet ihr mich, so haltet meine Gebote.\\u201d Johannes 14:15<\\\/em><\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>Antwort:<\\\/strong> Aufrichtige Christen werden ihr Leben ohne Verzug in \\u00dcbereinstimmung mit Gottes Anweisungen bringen, weil sie ihn lieben. Sie sind sich bewusst, dass seine Gesetze zu ihrem Wohl und Gl\\u00fcck gegeben sind und um sie vor Krankheiten zu bewahren, die Satan \\u00fcber sie bringen m\\u00f6chte (Apostelgeschichte 10:38). Gottes Ratschl\\u00e4ge und Anweisungen sind immer zu unserm Wohl, ebenso wie die Anweisungen guter Eltern f\\u00fcr ihre Kinder. Und wenn wir einmal erkannt haben, was in den Augen Gottes richtig ist, wird er uns daf\\u00fcr zur Verantwortung ziehen. \\u201cWer nun Gutes zu tun wei\\u00df und es nicht tut, f\\u00fcr den ist es S\\u00fcnde.\\u201d Jakobus 4:17<\\\/p>\",\"title\":\"14. Was sollte jeder aufrichtige Christ sogleich anstreben?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_rechts size-thumbnail wp-image-10171 alignright\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q15-BallAndChain-Man-150x150.jpg\\\" alt=\\\"15. Ich mache mir Sorgen, weil einige meiner \\u00fcblen Gewohnheiten mich so fest im Griff haben. Was soll ich tun?\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/> <em>\\u201cAllen aber, die ihn aufnahmen, denen gab er das Anrecht, Kinder Gottes zu werden.\\u201d Johannes 1:12 \\u201cIch vermag alles durch den, der mich stark macht,\\u2026 Christus.\\u201d Philipper 4:13<\\\/em><\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>Antwort:<\\\/strong> Gehen Sie mit all diesen Gewohnheiten zu Christus und legen Sie sie ihm zu F\\u00fcssen. Er wird ihnen mit Freuden ein neues Herz und die notwendige Kraft schenken, um mit jeder \\u00fcblen Gewohnheit zu brechen und ein Sohn oder eine Tochter Gottes zu werden (Hesekiel 11:18.19). Wie froh machend ist die Gewissheit, dass \\u201cmit Gott alle Dinge m\\u00f6glich sind.\\u201d Markus 10:27 Jesus sagt: \\u201cund wer zu mir kommt, den werde ich nicht hinaussto\\u00dfen\\u2026\\u201d Johannes 6:37 Jesus ist bereit, die Ketten zu sprengen, mit denen wir gebunden sind. Er sehnt sich danach, uns frei zu machen, sofern wir unsere Zustimmung dazu geben. Unsere \\u00c4ngste, \\u00fcblen Gewohnheiten und nerv\\u00f6sen Spannungen werden verschwinden, wenn wir seine Gebote halten. Er sagt: \\u201cDies habe ich zu euch geredet, damit \\u2026 eure Freude v\\u00f6llig werde.\\u201d Johannes 15:11 Der Teufel behauptet, dass im Ungehorsam wahre Freiheit zu finden sei, doch das ist ein Trugschluss (Johannes 8:44).<\\\/p>\",\"title\":\"15. Ich mache mir Sorgen, weil einige meiner \\u00fcblen Gewohnheiten mich so fest im Griff haben. Was soll ich tun?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><img loading=\\\"lazy\\\" class=\\\"bild_links size-thumbnail wp-image-10171 alignleft\\\" src=\\\"wp-content\\\/uploads\\\/2021\\\/06\\\/ba-gks-sg13-q16-Heaven-MeadowPlay-150x150.jpg\\\" alt=\\\"16. Welche froh machenden Verhei\\u00dfungen werden uns bez\\u00fcglich Gottes neuem Reich gegeben?\\\" width=\\\"150\\\" height=\\\"150\\\" \\\/> <em>\\u201cUnd kein Einwohner wird sagen: Ich bin schwach.\\u201d Jesaja 33:24 \\u201cund der Tod wird nicht mehr sein, weder Leid noch Geschrei noch Schmerz wird mehr sein;\\u201d Offenbarung 21:4 \\u201caber die auf den HERRN harren, kriegen neue Kraft, dass sie auffahren mit Fl\\u00fcgeln wie Adler, dass sie laufen und nicht matt werden, dass sie wandeln und nicht m\\u00fcde werden.\\u201d Jesaja 40:31<\\\/em><\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>Antwort:<\\\/strong> Die Bewohner von Gottes neuem Reich werden nach seinen Gesundheitsgesetzen leben. Dort wird es keine Krankheiten geben. Sie werden mit nie endender Kraft und Jugend gesegnet sein und in der Gemeinschaft mit Gott in unaussprechlicher Freude und Gl\\u00fcck in alle Ewigkeit leben.<\\\/p>\",\"title\":\"16. Welche froh machenden Verhei\\u00dfungen werden uns bez\\u00fcglich Gottes neuem Reich gegeben?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p><strong>Antwort:<\\\/strong><\\\/p>\",\"title\":\"17. Da ein gesunder Lebensstil tats\\u00e4chlich Teil der biblischen Lehre ist, bin ich bereit, Gottes Gesundheitsgesetze zu befolgen.\"}}]}]}]},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"\n\n<h4>Fragen zum Nachdenken<\\\/h4>\",\"title_element\":\"h1\"}},{\"type\":\"accordion\",\"props\":{\"collapsible\":true,\"content_column_breakpoint\":\"m\",\"css\":\"p strong{color: #92be56!important;}\",\"image_align\":\"top\",\"image_grid_breakpoint\":\"m\",\"image_grid_width\":\"1-2\",\"image_svg_color\":\"emphasis\",\"link_style\":\"default\",\"link_text\":\"\",\"multiple\":true,\"show_image\":true,\"show_link\":true},\"children\":[{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>Dieser Schriftabschnitt (Vers 3) bezieht sich auf Speisen, die \\u201cGott geschaffen hat, zu nehmen mit Danksagung\\u201d den Gl\\u00e4ubigen. Diese Speisen sind rein, wie wir bereits entdeckt haben und sind in 3.Mose 11 und in 5.Mose 14 aufgelistet. Vers 4 macht deutlich, dass alle Kreatur Gottes gut und nicht verwerflich ist, sofern sie unter den Kreaturen sind, die \\u201cmit Danksagung empfangen werden\\u201d (d.h. die reinen Tiere). Vers 5 sagt, warum diese Tiere (oder Speisen) in Ordnung sind: sie sind \\u201cgeheiligt\\u201d durch das Wort Gottes, welches diese als rein erkl\\u00e4rt, und durch ein \\u201cDankgebet\\u201d. Bitte beachten Sie aber, dass Gott jene vernichten wird, welche \\u201csich selbst heiligen\\u201d, w\\u00e4hrend sie unreine Speisen essen (Jesaja 66:17).<\\\/p>\",\"title\":\"1. In 1.Timotheus 4:4 steht: 'Denn alles, was Gott geschaffen hat, ist gut, und nichts ist verwerflich, wenn es mit Danksagung empfangen wird.' Wie ist diese Aussage zu verstehen?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>In Matth\\u00e4us 15:1-20 geht es um das Thema des Essens ohne vorheriges Waschen der H\\u00e4nde (Vers 2). Es geht hier nicht ums Essen, sondern ums Waschen. Die Schriftgelehrten unterwiesen die Leute, dass jedes Essen, das ohne vorheriges, besonderes Waschritual eingenommen werde, den Menschen verunreinige. Jesus erkl\\u00e4rte die zeremoniellen Waschungen jedoch als bedeutungslos. In Vers 19 z\\u00e4hlt er gewisse \\u00dcbel auf \\u2013 Mord, Ehebruch, Dieberei, etc. Dann schlussfolgerte er: \\u201cDas sind die St\\u00fccke, die den Menschen verunreinigen. Aber mit ungewaschenen H\\u00e4nden essen verunreinigt den Menschen nicht.\\u201d Vers 20<\\\/p>\",\"title\":\"2. In Matth\\u00e4us 15:11 lesen wir: 'Nicht das, was zum Mund hineinkommt, verunreinigt den Menschen, sondern was aus dem Mund herauskommt, das verunreinigt den Menschen.' Wie ist dies zu verstehen?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>Nein! In dieser Vision geht es nicht um Tiere, sondern um Menschen. Gott gab Petrus diese Vision, um ihm verst\\u00e4ndlich zu machen, dass die Heiden nicht unrein w\\u00e4ren, wie die Juden meinten. Gott hatte Kornelius, einen Heiden, angewiesen, M\\u00e4nner zu Petrus zu schicken. Petrus h\\u00e4tte es jedoch abgelehnt, diese zu empfangen, h\\u00e4tte Gott ihm nicht zuvor diese Vision gegeben, denn das j\\u00fcdische Gesetz verbot es, Heiden ins Haus zu nehmen (Vers 28). Als die M\\u00e4nner ankamen, wurden sie von Petrus aufgenommen. Dabei erkl\\u00e4rte er ihnen, dass er dies normalerweise nicht getan h\\u00e4tte, w\\u00fcrde Gott ihm nicht gezeigt haben, dass \\u201ckein Mensch gemein oder unrein zu hei\\u00dfen ist.\\u201d Vers 28. Im n\\u00e4chsten Kapitel (Apostelgeschichte 11), wurde Petrus von den Gemeindegliedern wegen seines Umgangs mit den Heiden getadelt. Da erz\\u00e4hlte er ihnen die ganze Geschichte mit der Vision und deren Bedeutung. In Apostelgeschichte 11:18 lesen wir dann: \\u201cDa sie das h\\u00f6rten, schwiegen sie still und lobten Gott und sprachen: So hat Gott auch den Heiden Bu\\u00dfe gegeben zum Leben!\\u201d<\\\/p>\",\"title\":\"3. Wurden in der Vision des Petrus nicht alle Tiere von Jesus gereinigt nach dem Bericht in Apostelgeschichte 10?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>Gott schuf dieses aus demselben Grund wie den Bussard \\u2013 als einen Aasfresser, um die Umwelt von Abfall zu s\\u00e4ubern. Und das Schwein kommt dieser Bestimmung in bewunderungsw\\u00fcrdiger Weise nach.<\\\/p>\",\"title\":\"4. Wof\\u00fcr hat denn Gott das Schwein geschaffen, wenn nicht zur Speise?\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>In den Versen 3-6 geht es um Menschen, die gewisse Dinge essen, die andere meiden. In diesem Abschnitt wird weder dem einen noch dem andern Recht gegeben, sondern der Rat erteilt, einander nicht zu verurteilen. Gott sollte die Sache beurteilen (Verse 4,10-12). In den Versen 14 und 20 geht es um Speisen, die erst den G\\u00f6tzen dargebracht worden waren (was sie zeremoniell unrein machte) \\u2013 nicht um reine oder unreine Tiere von 3.Mose 11. (Bitte lesen Sie 1.Korinther 8:1.4.10.13). Es geht in dieser Diskussion darum, dass vorheriges Darbringen der Speisen den G\\u00f6tzen diese Speisen nicht \\u201cunrein\\u201d machten, weil ein G\\u00f6tze \\u201cnichts in der Welt ist.\\u201d 1.Korinther 8:4 Doch wenn sich ein Mensch ein Gewissen dar\\u00fcber macht, dann sollte er es besser nicht anr\\u00fchren. Selbst wenn ein Bruder Ansto\\u00df daran n\\u00e4hme, sollte er darauf verzichten.<\\\/p>\",\"title\":\"5. In R\\u00f6mer 14:3.14.20 steht: 'Wer isst, verachte den nicht, der nicht isst.' 'Ich wei\\u00df, \\u2026 dass nichts an und f\\u00fcr sich unrein ist.' 'Es ist zwar alles rein, aber...' Wie kann dies erkl\\u00e4rt werden? In den Versen 3-6 geht es um Mensch\"}},{\"type\":\"accordion_item\",\"props\":{\"content\":\"\n\n<p>Es geht dabei um Leben und Tod, weil der Gehorsam mit im Spiel ist. \\u201cund nachdem er zur Vollendung gelangt ist, ist er allen, die ihm gehorchen, der Urheber ewigen Heils geworden.\\u201d Hebr\\u00e4er 5:9 \\u201cNicht jeder, der zu mir sagt: Herr, Herr! wird in das Reich der Himmel eingehen, sondern wer den Willen meines Vaters im Himmel tut.\\u201d Matth\\u00e4us 7:21 Es geht hier um die Liebe, die wir zu Christus haben, denn er sagt: \\u201cLiebet ihr mich, so haltet meine Gebote.\\u201d Johannes 14:15 Wenn wir den Herrn wirklich lieben, dann gehorchen wir ihm gerne, ohne Ausfl\\u00fcchte oder Entschuldigungen zu suchen. Es handelt sich hier um den gr\\u00f6\\u00dften Pr\\u00fcfstein.<\\\/p>\",\"title\":\"6. Sind Gesundheitsgesetze, Essen und Trinken f\\u00fcr mich pers\\u00f6nlich wirklich von Bedeutung? Gen\\u00fcgt es nicht, wenn ich den Herrn liebe?\"}}]}]}]},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"\n\n<h4>QUIZ FRAGEN<\\\/h4>\",\"title_element\":\"h1\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"Teste mit diesem Quiz, ob Du das Anliegen der Bibel zu diesem Thema verstanden hast.\",\"margin\":\"default\"}},{\"type\":\"html\",\"props\":{\"content\":\"[ays_quiz id=\\\"10\\\"]\"}}]}],\"props\":{\"class\":\"de-only\"}}],\"name\":\"Inhalt\"},{\"type\":\"section\",\"props\":{\"class\":\"de-only\",\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"small\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"module_position\",\"props\":{\"breakpoint\":\"m\",\"content\":\"builder-2\",\"layout\":\"stack\"},\"name\":\"CTA: Lebenshilfe & E-Coach \"}]}]}],\"name\":\"Call to Action\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"DAS K\\u00d6NNTE DICH AUCH INTERESSIEREN\",\"text_align\":\"center\",\"title_element\":\"h1\",\"title_style\":\"h3\"}},{\"type\":\"gallery\",\"props\":{\"filter_align\":\"left\",\"filter_all\":true,\"filter_grid_breakpoint\":\"m\",\"filter_grid_width\":\"auto\",\"filter_position\":\"top\",\"filter_style\":\"tab\",\"grid_column_gap\":\"small\",\"grid_default\":\"1\",\"grid_medium\":\"3\",\"grid_row_gap\":\"small\",\"grid_small\":\"2\",\"image_hover_box_shadow\":\"small\",\"image_orientation\":false,\"image_transition\":\"scale-up\",\"item_animation\":true,\"link_style\":\"text\",\"link_text\":\"\",\"margin\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"overlay_hover\":false,\"overlay_link\":true,\"overlay_mode\":\"cover\",\"overlay_position\":\"center\",\"overlay_style\":\"overlay-primary\",\"overlay_transition\":\"fade\",\"parallax_easing\":\"1\",\"show_content\":false,\"show_hover_image\":true,\"show_link\":true,\"show_meta\":false,\"show_title\":true,\"text_align\":\"center\",\"text_color\":\"light\",\"title_element\":\"h5\",\"title_hover_style\":\"reset\",\"title_style\":\"h5\"},\"children\":[{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/2021\\\/03\\\/bzg-interesse-stadt.jpg\",\"link\":\"beziehung-zu-gott\\\/was-ist-lebenserfolg\",\"title\":\"Was ist Lebenserfolg?\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/2021\\\/03\\\/bzg-interesse-bibel.jpg\",\"link\":\"beziehung-zu-gott\\\/was-ist-das-hauptanliegen-der-bibel\",\"title\":\"Was ist das Hauptanliegen der Bibel?\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/2021\\\/03\\\/bzg-interesse-herz.jpg\",\"link\":\"wege-zum-ziel\\\/sinnbilder-der-liebe-gottes\",\"title\":\"Sinnbilder der Liebe Gottes\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/2021\\\/03\\\/bzg-interesse-kreuz.jpg\",\"link\":\"beziehung-zu-gott\\\/jesus-einzigartig-und-unvergleichlich\",\"title\":\"Jesus von Nazareth\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/2021\\\/03\\\/bzg-interesse-taube.jpg\",\"link\":\"beziehung-zu-gott\\\/leben-in-der-kraft-gottes\",\"title\":\"Leben in der Kraft Gottes\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/2021\\\/03\\\/bzg-interesse-beten.jpg\",\"link\":\"zweifel-oder-glaube\\\/ich-will-gott-erleben\",\"title\":\"Ich will Gott erleben\"}}]}]}]}],\"name\":\"Weiteres Angebot\"}],\"version\":\"4.3.5\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gottes kostenloser Gesundheitsplan Gute medizinische Versorgung ist unbezahlbar \u2013 doch w\u00e4re es nicht besser, wenn wir keine \u00c4rzte mehr ben\u00f6tigten? Wussten Sie, dass es einen bew\u00e4hrten Weg gibt, um viele \u00c4rzte arbeitslos zu machen? Tragen Sie Sorge zu Ihrem K\u00f6rper! Wissenschaftler warnen un\u00fcberh\u00f6rbar vor hohem Cholesterin, Tabak, Stress, \u00dcbergewicht und Alkohol. Warum also Ihr Gl\u00fcck [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2516,"parent":28,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-692","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/gotterfahren.info\/en\/wp-json\/wp\/v2\/pages\/692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gotterfahren.info\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gotterfahren.info\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gotterfahren.info\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/gotterfahren.info\/en\/wp-json\/wp\/v2\/comments?post=692"}],"version-history":[{"count":0,"href":"https:\/\/gotterfahren.info\/en\/wp-json\/wp\/v2\/pages\/692\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/gotterfahren.info\/en\/wp-json\/wp\/v2\/pages\/28"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gotterfahren.info\/en\/wp-json\/wp\/v2\/media\/2516"}],"wp:attachment":[{"href":"https:\/\/gotterfahren.info\/en\/wp-json\/wp\/v2\/media?parent=692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}